{"id":10173,"date":"2024-09-09T11:10:40","date_gmt":"2024-09-09T07:40:40","guid":{"rendered":"https:\/\/www.faraketab.ir\/blog\/?p=10173"},"modified":"2024-09-03T16:14:41","modified_gmt":"2024-09-03T12:44:41","slug":"%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa","status":"publish","type":"post","link":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/","title":{"rendered":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0"},"content":{"rendered":"<p><strong>\u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/strong>\u060c \u0627\u062b\u0631 \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633 \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631\u0622\u0645\u062f\u0647 \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u062b\u0631 \u0627\u0632 \u06a9\u064f\u0647\u0646\u200c\u062a\u0631\u06cc\u0646\u00a0\u0631\u0645\u0627\u0646\u200c\u0647\u0627 \u062f\u0631 \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0627\u0631\u0648\u067e\u0627\u06cc\u06cc\u00a0\u0627\u0633\u062a.\u00a0\u0633\u0631\u0648\u0627\u0646\u062a\u0633\u060c \u0628\u062e\u0634 \u0627\u0648\u0644\u00a0<em>\u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/em> \u0631\u0627 \u062f\u0631 \u0632\u0646\u062f\u0627\u0646 \u0646\u0648\u0634\u062a\u061b \u06a9\u0647 \u0628\u062e\u0634 \u0627\u0648\u0644 \u0646\u062e\u0633\u062a\u06cc\u0646 \u0628\u0627\u0631 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f6\u06f0\u06f5 \u0645\u06cc\u0644\u0627\u062f\u06cc \u0648 \u0628\u062e\u0634 \u062f\u0648\u0645 \u0646\u06cc\u0632 \u062f\u0631 \u06f1\u06f6\u06f1\u06f5 \u0645\u06cc\u0644\u0627\u062f\u06cc \u062f\u0631 \u0645\u0627\u062f\u0631\u06cc\u062f\u060c \u0686\u0627\u067e \u0648 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f. \u0646\u0633\u062e\u0647 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u0635\u0648\u0631\u062a \u0631\u0627\u06cc\u06af\u0627\u0646 \u0628\u0631\u0627\u06cc \u062f\u0642\u0627\u06cc\u0642\u06cc \u0645\u062d\u062f\u0648\u062f \u062f\u0631 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u0645\u0637\u0627\u0644\u0639\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u062f\u0631 \u0645\u0648\u0631\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a \u0642\u0636\u0627\u0648\u062a \u06a9\u0646\u06cc\u062f.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\" >\u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA_%D9%86%D9%85%D8%A7%D8%AF_%DA%86%DB%8C%D8%B3%D8%AA\" >\u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0\u0646\u0645\u0627\u062f \u0686\u06cc\u0633\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#%D8%AE%D9%84%D8%A7%D8%B5%D9%87_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\" >\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%AA%D8%B1%D8%AC%D9%85%D9%87_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\" >\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%AA%D8%B1%D8%AC%D9%85%D9%87_%D8%AF%D9%88%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\" >\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u062f\u0648\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%88%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA_%D8%AA%D8%B1%D8%AC%D9%85%D9%87_%DA%A9%DB%8C%D9%88%D9%85%D8%B1%D8%AB_%D9%BE%D8%A7%D8%B1%D8%B3%D8%A7\" >\u06a9\u062a\u0627\u0628 \u062f\u0648\u0646 \u06a9\u06cc\u0634\u0648\u062a \u062a\u0631\u062c\u0645\u0647 \u06a9\u06cc\u0648\u0645\u0631\u062b \u067e\u0627\u0631\u0633\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#%D8%AF%D9%88%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA_%D8%AC%D9%84%D8%AF_%D8%A7%D9%88%D9%84_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA%D8%8C_%D8%A7%D8%AB%D8%B1_%D9%85%DB%8C%DA%AF%D9%84_%D8%AF_%D8%B3%D8%B1%D9%88%D8%A7%D9%86%D8%AA%D8%B3_%D9%88_%D8%A8%D8%A7_%D8%AA%D8%B1%D8%AC%D9%85%D9%87_%DA%A9%DB%8C%D9%88%D9%85%D8%B1%D8%AB_%D9%BE%D8%A7%D8%B1%D8%B3%D8%A7%DB%8C_%D8%A8%D9%87_%D8%B1%D8%B4%D8%AA%D9%87_%D8%AA%D8%AD%D8%B1%DB%8C%D8%B1_%D8%AF%D8%B1%D8%A2%D9%85%D8%AF%D9%87_%D9%88_%D8%AF%D8%B1_%D8%A7%D9%86%D8%AA%D8%B4%D8%A7%D8%B1%D8%A7%D8%AA_%D8%B1%D9%88%D8%B2%DA%AF%D8%A7%D8%B1_%D8%A8%D9%87_%D9%86%D8%B4%D8%B1_%D9%88_%D8%AF%D8%B1_%D8%AF%D8%B3%D8%AA%D8%B1%D8%B3_%D8%B9%D9%84%D8%A7%D9%82%D9%87_%D9%85%D9%86%D8%AF%D8%A7%D9%86_%D9%82%D8%B1%D8%A7%D8%B1_%DA%AF%D8%B1%D9%81%D8%AA%D9%87_%D8%A7%D8%B3%D8%AA_%D9%85%D8%B9_%D8%B1%D9%88%D8%B2%DA%AF%D8%A7%D8%B1_%D9%86%D8%A7%D8%B4%D8%B1_%D9%85%DB%8C%DA%AF%D9%84_%D8%AF_%D8%B3%D8%B1%D9%88%D8%A7%D9%86%D8%AA%D8%B3_%D9%86%D9%88%DB%8C%D8%B3%D9%86%D8%AF%D9%87_%D9%BE%DB%8C%D8%B4_%D9%86%D9%85%D8%A7%DB%8C%D8%B4_%D9%88_%D8%AE%D8%B1%DB%8C%D8%AF_%D9%BE%DB%8C%D8%B4_%D9%86%D9%85%D8%A7%DB%8C%D8%B4_%D9%88_%D8%AE%D8%B1%DB%8C%D8%AF_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA_%D8%AA%D8%B1%D8%AC%D9%85%D9%87_%D8%B0%D8%A8%DB%8C%D8%AD_%D8%A7%D9%84%D9%84%D9%87_%D9%85%D9%86%D8%B5%D9%88%D8%B1%DB%8C\" >\u062f\u0648\u0646 \u06a9\u06cc\u0634\u0648\u062a (\u062c\u0644\u062f \u0627\u0648\u0644)        \n\t                                        \n\t                                         \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c \u0627\u062b\u0631 \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633 \u0648 \u0628\u0627 \u062a\u0631\u062c\u0645\u0647 \u06a9\u06cc\u0648\u0645\u0631\u062b \u067e\u0627\u0631\u0633\u0627\u06cc \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631\u0622\u0645\u062f\u0647 \u0648 \u062f\u0631 \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0631\u0648\u0632\u06af\u0627\u0631 \u0628\u0647 \u0646\u0634\u0631 \u0648 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0639\u0644\u0627\u0642\u0647 \u0645\u0646\u062f\u0627\u0646 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a.\n\n\u0645\u0639...\n\t                                    \n\t                                    \n            \n            \n                \u0631\u0648\u0632\u06af\u0627\u0631\n                \u0646\u0627\u0634\u0631\n            \n        \n            \n            \n                \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633\n                \u0646\u0648\u06cc\u0633\u0646\u062f\u0647\n            \n        \n\t                                    \u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0634 \u0648 \u062e\u0631\u06cc\u062f\n\t                                \n\t                                 \u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0634 \u0648 \u062e\u0631\u06cc\u062f\n\t                            \n\t                        \n\u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a \u062a\u0631\u062c\u0645\u0647\u00a0\u0630\u0628\u06cc\u062d \u0627\u0644\u0644\u0647 \u0645\u0646\u0635\u0648\u0631\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#%D8%AC%D9%85%D9%84%D8%A7%D8%AA_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\" >\u062c\u0645\u0644\u0627\u062a \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#%D8%AF%D8%A7%D9%86%D9%84%D9%88%D8%AF_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\" >\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\"><\/span>\u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong>\u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a \u06a9\u062a\u0627\u0628\u00a0<\/strong>\u0645\u0634\u0647\u0648\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0634\u0647\u0631\u062a \u0622\u0646 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0631\u062e\u062f\u0627\u062f\u0647\u0627 \u0648 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u06af\u0648\u0646\u0627\u06af\u0648\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0631\u0648\u0627\u06cc\u062a \u0622\u0646 \u0647\u0627 \u067e\u0631\u062f\u0627\u062e\u062a\u0647 \u0645\u06cc \u0634\u0648\u062f.<br \/>\n\u0645\u062c\u0645\u0648\u0639\u0647 \u06cc \u0631\u0645\u0627\u0646 \u00ab\u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00bb \u0628\u0647 \u0631\u0648\u0627\u06cc\u062a \u0627\u0635\u06cc\u0644 \u0632\u0627\u062f\u0647 \u0627\u06cc \u0628\u0647 \u0646\u0627\u0645 \u062f\u0648\u0646 \u06a9\u06cc\u062e\u0648\u062a\u0647 \u062f\u0644\u0627\u0645\u0627\u0646\u0686\u0627 \u0645\u06cc \u067e\u0631\u062f\u0627\u0632\u062f \u06a9\u0647 \u062f\u0631 \u0631\u0648\u0632\u06af\u0627\u0631\u06cc \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0622\u0646 \u0634\u0647\u0633\u0648\u0627\u0631\u06cc \u0648 \u062f\u0644\u0627\u0648\u0631\u06cc \u062e\u0628\u0631\u06cc \u0646\u06cc\u0633\u062a \u0627\u0645\u0627 \u0628\u0627 \u0648\u062c\u0648\u062f \u0627\u06cc\u0646 \u0642\u0636\u0627\u06cc\u0627\u060c \u0634\u062e\u0635\u06cc\u062a \u0627\u0635\u0644\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u0628\u0627 \u0627\u0631\u0627\u062f\u0647 \u0627\u06cc \u0645\u062d\u06a9\u0645\u060c \u062a\u0635\u0645\u06cc\u0645 \u062f\u0627\u0631\u062f \u0627\u06cc\u0646 \u062e\u0644\u0627 \u0631\u0627 \u067e\u0631 \u06a9\u0631\u062f\u0647 \u0648 \u06af\u0633\u062a\u0631\u0647 \u06cc \u0627\u06cc\u0646 \u0646\u0648\u0639 \u062f\u0644\u0627\u0648\u0631\u06cc \u0647\u0627 \u0631\u0627 \u0627\u0632 \u0646\u0648 \u0628\u0631 \u067e\u0627 \u06a9\u0646\u062f \u06a9\u0647 \u0634\u0627\u06cc\u062f \u0622\u0646 \u0631\u0648\u06cc\u0627\u0647\u0627\u06cc\u06cc \u0631\u0627 \u06a9\u0647 \u062f\u0631 \u0633\u0631 \u067e\u0631\u0648\u0631\u0627\u0646\u062f\u0647 \u0628\u0647 \u062d\u0642\u06cc\u0642\u062a \u0645\u0628\u062f\u0644 \u0634\u0648\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA_%D9%86%D9%85%D8%A7%D8%AF_%DA%86%DB%8C%D8%B3%D8%AA\"><\/span>\u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0<strong>\u0646\u0645\u0627\u062f \u0686\u06cc\u0633\u062a<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u00ab\u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00bb\u00a0\u0646\u0645\u0627\u062f\u00a0\u0627\u0646\u0633\u0627\u0646\u06cc \u0622\u0631\u0645\u0627\u0646\u06cc \u0627\u0633\u062a\u060c \u0642\u0647\u0631\u0645\u0627\u0646 \u062e\u0648\u062f\u062e\u0648\u0627\u0646\u062f\u0647 \u0627\u06cc \u06a9\u0647 \u0645\u06cc \u062e\u0648\u0627\u0647\u062f \u0628\u0647 \u0627\u0635\u0644\u0627\u062d \u0627\u0645\u0648\u0631 \u0628\u067e\u0631\u062f\u0627\u0632\u062f. \u0641\u0631\u062f\u06cc \u0639\u0645\u0644\u06af\u0631\u0627 \u06a9\u0647 \u0686\u0648\u0646 \u0627\u0632 \u00ab\u0648\u0627\u0642\u0639\u064a\u062a \u0647\u0627\u00bb \u0641\u0627\u0635\u0644\u0647 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a \u0628\u0627 \u00ab\u0645\u062c\u0627\u0632\u0647\u0627\u00bb \u062f\u0633\u062a \u0648 \u067e\u0646\u062c\u0647 \u0646\u0631\u0645 \u0645\u06cc \u06a9\u0646\u062f. \u0627\u0648 \u0647\u062f\u0641\u0645\u0646\u062f \u0627\u0633\u062a \u0648 \u0628\u0631\u0627\u06cc \u0647\u062f\u0641\u06cc \u06a9\u0647 \u0645\u06cc \u0634\u0646\u0627\u0633\u062f \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0622\u0628 \u0648 \u0622\u062a\u0634 \u0645\u06cc \u0632\u0646\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AE%D9%84%D8%A7%D8%B5%D9%87_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\"><\/span>\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0627\u0633\u062a\u0627\u0646\u060c \u062f\u0627\u0633\u062a\u0627\u0646 \u062f\u0644\u0627\u0648\u0631\u06cc \u0647\u0627\u06cc \u00ab\u062f\u0648\u0646 \u06a9\u06cc\u062e\u0648\u062a\u0647 \u062f\u0644\u0627\u0645\u0627\u0646\u0686\u0627\u00bb \u0627\u0632 \u0627\u0635\u06cc\u0644 \u0632\u0627\u062f\u06af\u0627\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u0648\u062c\u0648\u062f \u0632\u0646\u062f\u06af\u06cc \u0645\u0639\u0645\u0648\u0644\u06cc\u060c \u0642\u0635\u062f \u062f\u0627\u0631\u062f \u0631\u0632\u0645 \u062c\u0646\u06af\u06cc \u0628\u067e\u0648\u0634\u062f \u0648 \u062f\u0644\u0627\u0648\u0631\u06cc \u0628\u0627\u0634\u062f \u0627\u0633\u0628 \u0633\u0648\u0627\u0631 \u0648 \u0634\u0645\u0634\u06cc\u0631 \u0628\u0647 \u062f\u0633\u062a \u0648 \u0628\u0634\u062a\u0627\u0628\u062f \u0628\u0647 \u0633\u0648\u06cc \u0622\u06cc\u0646\u062f\u0647 \u0627\u06cc \u06a9\u0647 \u062f\u0631 \u0630\u0647\u0646 \u062e\u0648\u06cc\u0634 \u0631\u0633\u0645 \u0646\u0645\u0648\u062f\u0647 \u0627\u0645\u0627 \u062f\u0646\u06cc\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc\u060c \u0647\u0645 \u0686\u0648\u0646 \u0631\u0648\u06cc\u0627\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0630\u0647\u0646 \u062e\u0648\u06cc\u0634 \u0633\u0627\u062e\u062a\u0647 \u0628\u0627 \u0627\u0648 \u0645\u0647\u0631\u0628\u0627\u0646 \u0646\u0628\u0648\u062f\u0647 \u0648 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a \u062f\u0627\u0633\u062a\u0627\u0646 \u0645\u0627 \u0631\u0627 \u0628\u0647 \u0631\u0648\u06cc\u0627\u0631\u0648\u06cc\u06cc \u062d\u0642\u06cc\u0642\u062a \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0634\u0627\u0646\u062f.<br \/>\n<strong>\u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c\u00a0<\/strong>\u0634\u0627\u0645\u0644 \u0645\u0627\u062c\u0631\u0627\u0647\u0627 \u0648 \u0631\u062e\u062f\u0627\u062f \u0647\u0627\u06cc \u06af\u0648\u0646\u0627\u06af\u0648\u0646\u06cc \u0646\u0638\u06cc\u0631\u061b \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627 \u0648 \u0631\u0641\u062a\u0627\u0631\u0647\u0627\u06cc \u0646\u062c\u06cc\u0628 \u0632\u0627\u062f\u0647 \u0646\u0627\u0645\u062f\u0627\u0631 \u062f\u0648\u0646 \u06a9\u06cc\u062e\u0648\u062a\u0647 \u062f\u0644\u0627\u0645\u0627\u0646\u0686\u0627\u060c \u0646\u062e\u0633\u062a\u06cc\u0646 \u0639\u0632\u06cc\u0645\u062a \u062f\u0648\u0646 \u06a9\u06cc\u062e\u0648\u062a\u0647 \u0627\u0632 \u0645\u0646\u0637\u0642\u0647 \u0644\u0627\u0645\u0627\u0646\u0686\u0627\u060c \u0634\u06cc\u0648\u0647 \u062f\u0644\u067e\u0630\u06cc\u0631 \u0646\u06cc\u0644 \u0628\u0647 \u0645\u0642\u0627\u0645 \u067e\u0647\u0644\u0648\u0627\u0646\u06cc\u060c \u0645\u0627\u062c\u0631\u0627\u0647\u0627\u06cc \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u067e\u0633 \u0627\u0632 \u062a\u0631\u06a9 \u06a9\u0627\u0631\u0648\u0627\u0646\u0633\u0631\u0627\u060c \u0627\u062f\u0627\u0645\u0647 \u0646\u0627\u06a9\u0627\u0645\u06cc \u0647\u0627\u06cc \u067e\u0647\u0644\u0648\u0627\u0646\u060c \u062a\u0641\u062a\u06cc\u0634 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u0646\u062c\u06cc\u0628 \u0632\u0627\u062f\u0647 \u0641\u0631\u0632\u0627\u0646\u0647 \u062a\u0648\u0633\u0637 \u06a9\u0634\u06cc\u0634 \u0648 \u0633\u0644\u0645\u0627\u0646\u06cc\u060c \u062f\u0648\u0645\u06cc\u0646 \u0645\u0627\u062c\u0631\u0627\u06cc \u067e\u0647\u0644\u0648\u0627\u0646 \u062f\u0648\u0646 \u06a9\u06cc\u062e\u0648\u062a\u0647 \u062f\u0644\u0627\u0645\u0627\u0646\u0686\u0627\u060c \u067e\u06cc\u0631\u0648\u0632\u06cc \u0628\u0631 \u0622\u0633\u06cc\u0627\u0628 \u0647\u0627\u06cc \u0628\u0627\u062f\u06cc \u0648 \u0633\u0627\u06cc\u0631 \u0645\u0627\u062c\u0631\u0627\u0647\u0627\u060c \u067e\u0627\u06cc\u0627\u0646 \u0646\u0628\u0631\u062f \u0647\u0631\u0627\u0633\u0646\u0627\u06a9 \u0628\u06cc\u0633\u06a9\u0627\u0646\u06cc\u0627\u06cc\u06cc \u0648 \u062f\u0644\u0627\u0648\u0631 \u0644\u0627\u0645\u0627\u0646\u0686\u0627\u060c \u06af\u0641\u062a\u06af\u0648\u0647\u0627\u06cc \u062c\u0627\u0644\u0628 \u0645\u06cc\u0627\u0646 \u062f\u0648\u0646 \u06a9\u06cc\u062e\u0648\u062a\u0647 \u0648 \u0633\u0627\u0646\u0686\u0648 \u067e\u0627\u0646\u0632\u0627\u060c \u0645\u0627\u062c\u0631\u0627\u06cc \u062f\u0648\u0646 \u06a9\u06cc\u062e\u0648\u062a\u0647 \u0648 \u0686\u0648\u067e\u0627\u0646\u0627\u0646\u060c \u0645\u0627\u062c\u0631\u0627\u06cc\u06cc \u06a9\u0647 \u0686\u0648\u067e\u0627\u0646 \u0628\u0631\u0627\u06cc \u062f\u0648\u0646 \u06a9\u06cc\u062e\u0648\u062a\u0647 \u0648 \u0647\u0645\u06a9\u0627\u0631\u0627\u0646 \u062e\u0648\u062f \u062a\u0639\u0631\u06cc\u0641 \u06a9\u0631\u062f\u060c \u067e\u0627\u06cc\u0627\u0646 \u0645\u0627\u062c\u0631\u0627\u0647\u0627\u06cc \u0645\u0627\u0631\u0633\u0644\u0627\u06cc \u0686\u0648\u067e\u0627\u0646 \u0648 \u0633\u0627\u06cc\u0631 \u0631\u0648\u06cc\u062f\u0627\u062f\u0647\u0627 \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0647 \u0622\u0646 \u0647\u0627 \u067e\u0631\u062f\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%AA%D8%B1%D8%AC%D9%85%D9%87_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\"><\/span>\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0645\u062a\u0631\u062c\u0645\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0628\u0647 \u0633\u0631\u0627\u063a \u06a9\u062a\u0627\u0628 \u062f\u0648\u0646 \u06a9\u06cc\u0634\u0648\u062a \u0631\u0641\u062a\u0646\u062f \u062a\u0627 \u0646\u0633\u062e\u0647\u200c\u06cc \u062e\u0648\u062f\u0634\u0627\u0646 \u0631\u0627 \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0627\u0631\u0627\u0626\u0647 \u06a9\u0646\u0646\u062f. \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0631\u0648\u0632\u06af\u0627\u0631 \u0627\u06cc\u0646 \u0627\u062b\u0631 \u0631\u0627 \u0628\u0627 \u062a\u0631\u062c\u0645\u0647\u200c\u06cc \u06a9\u06cc\u0648\u0645\u0631\u062b \u067e\u0627\u0631\u0633\u0627 \u0645\u0646\u062a\u0634\u0631 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0646\u06af\u0627\u0647 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0631\u0627 \u0628\u0627 \u062a\u0631\u062c\u0645\u0647 \u0630\u0628\u06cc\u062d \u0627\u0644\u0647 \u0645\u0646\u0635\u0648\u0631\u06cc \u0628\u0647 \u0686\u0627\u067e \u0631\u0633\u0627\u0646\u062f\u0647 \u0627\u0633\u062a \u0648 \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0646\u0634\u0631 \u062b\u0627\u0644\u062b \u0628\u0627 \u062a\u0631\u062c\u0645\u0647 \u0645\u062d\u0645\u062f \u0642\u0627\u0636\u06cc \u0646\u06cc\u0632 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0631\u0627 \u062a\u0631\u062c\u0645\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%AA%D8%B1%D8%AC%D9%85%D9%87_%D8%AF%D9%88%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\"><\/span>\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u062f\u0648\u0646 \u06a9\u06cc\u0634\u0648\u062a<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0645\u062e\u0627\u0637\u0628\u0627\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0648\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c \u0627\u0632 \u0627\u0645\u06a9\u0627\u0646 \u0645\u0637\u0627\u0644\u0639\u0647 \u0631\u0627\u06cc\u06af\u0627\u0646 \u06a9\u062a\u0627\u0628 \u0647\u0627\u06cc \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u0628\u0631\u0627\u06cc \u0645\u062f\u062a \u0645\u062d\u062f\u0648\u062f \u062f\u0631 \u0627\u067e\u0644\u06cc\u06a9\u06cc\u0634\u0646 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%88%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA_%D8%AA%D8%B1%D8%AC%D9%85%D9%87_%DA%A9%DB%8C%D9%88%D9%85%D8%B1%D8%AB_%D9%BE%D8%A7%D8%B1%D8%B3%D8%A7\"><\/span>\u06a9\u062a\u0627\u0628 \u062f\u0648\u0646 \u06a9\u06cc\u0634\u0648\u062a \u062a\u0631\u062c\u0645\u0647 \u06a9\u06cc\u0648\u0645\u0631\u062b \u067e\u0627\u0631\u0633\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><a href=\"https:\/\/www.faraketab.ir\/book\/16593-%D8%AF%D9%88%D9%86-%DA%A9%DB%8C%D8%B4%D9%88%D8%AA-%D8%AC%D9%84%D8%AF-%D8%A7%D9%88%D9%84#h_76012911611611722253553984\">\u06a9\u062a\u0627\u0628 \u062f\u0648\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/a> \u062a\u0631\u062c\u0645\u0647 \u06a9\u06cc\u0648\u0645\u0631\u062b \u067e\u0627\u0631\u0633\u0627\u060c \u0628\u0631\u06af\u0631\u062f\u0627\u0646 \u0627\u0632 \u0645\u062a\u0646 \u0627\u0635\u0644\u06cc \u0627\u0633\u067e\u0627\u0646\u06cc\u0648\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062a\u0648\u0633\u0637 \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0631\u0648\u0632\u06af\u0627\u0631\u060c \u062f\u0631 \u062f\u0648 \u062c\u0644\u062f \u0628\u0647 \u0686\u0627\u067e \u0631\u0633\u06cc\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0635\u0648\u0631\u062a \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0645\u0648\u062c\u0648\u062f \u0645\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<div class=\"special-product\">\n\t                            <div class=\"special-product__content\">\n\t                                <a class=\"special-product__thumbnail\" href=\"https:\/\/faraketab.ir\/book\/16593\" title=\"\u062f\u0648\u0646 \u06a9\u06cc\u0634\u0648\u062a (\u062c\u0644\u062f \u0627\u0648\u0644)\">\t                                   \n\t                                    \n\t                                    <picture >\n\t                                        <source type = \"image\/avif\" srcset = \"https:\/\/file1.cdn.faraketab.ir\/content_file\/content-1-16593-969707\/%D8%AF%D9%88%D9%86%20%DA%A9%DB%8C%D8%B4%D9%88%D8%AA%20%28%D8%AC%D9%84%D8%AF%20%D8%A7%D9%88%D9%84%29.jpg\" >\n\t                                        <source type = \"image\/webp\" srcset = \"https:\/\/file1.cdn.faraketab.ir\/content_file\/content-1-16593-969707\/%D8%AF%D9%88%D9%86%20%DA%A9%DB%8C%D8%B4%D9%88%D8%AA%20%28%D8%AC%D9%84%D8%AF%20%D8%A7%D9%88%D9%84%29.jpg\" >\n\t                                        <img class=\"product-thumbnail\" srcset = \"https:\/\/file1.cdn.faraketab.ir\/content_file\/content-1-16593-969707\/%D8%AF%D9%88%D9%86%20%DA%A9%DB%8C%D8%B4%D9%88%D8%AA%20%28%D8%AC%D9%84%D8%AF%20%D8%A7%D9%88%D9%84%29.jpg\" alt = \"\" title = \"\" >\n\t                                    <\/picture >\n\t                                    <div class=\"detail\" >\n\t                                        <div class=\"rate\"><i class='fa fa-star '><\/i><i class='fa fa-star '><\/i><i class='fa fa-star '><\/i><i class='fa fa-star '><\/i><i class='fa fa-star '><\/i><\/div >\n\t                                        <div class=\"type\" >\n\t                                           <i class='far fa-file active'><\/i>\n                    <i class='far fa-headphones '><\/i>\n                    <i class='far fa-book '><\/i>\n\t                                        <\/div >\n\t                                    <\/div >\n\t                                <\/a>\n\t                                <div class=\"special-product__details\" >\n\t                                    <div>\n\t                                        <h3 class=\"title\" ><span class=\"ez-toc-section\" id=\"%D8%AF%D9%88%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA_%D8%AC%D9%84%D8%AF_%D8%A7%D9%88%D9%84_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA%D8%8C_%D8%A7%D8%AB%D8%B1_%D9%85%DB%8C%DA%AF%D9%84_%D8%AF_%D8%B3%D8%B1%D9%88%D8%A7%D9%86%D8%AA%D8%B3_%D9%88_%D8%A8%D8%A7_%D8%AA%D8%B1%D8%AC%D9%85%D9%87_%DA%A9%DB%8C%D9%88%D9%85%D8%B1%D8%AB_%D9%BE%D8%A7%D8%B1%D8%B3%D8%A7%DB%8C_%D8%A8%D9%87_%D8%B1%D8%B4%D8%AA%D9%87_%D8%AA%D8%AD%D8%B1%DB%8C%D8%B1_%D8%AF%D8%B1%D8%A2%D9%85%D8%AF%D9%87_%D9%88_%D8%AF%D8%B1_%D8%A7%D9%86%D8%AA%D8%B4%D8%A7%D8%B1%D8%A7%D8%AA_%D8%B1%D9%88%D8%B2%DA%AF%D8%A7%D8%B1_%D8%A8%D9%87_%D9%86%D8%B4%D8%B1_%D9%88_%D8%AF%D8%B1_%D8%AF%D8%B3%D8%AA%D8%B1%D8%B3_%D8%B9%D9%84%D8%A7%D9%82%D9%87_%D9%85%D9%86%D8%AF%D8%A7%D9%86_%D9%82%D8%B1%D8%A7%D8%B1_%DA%AF%D8%B1%D9%81%D8%AA%D9%87_%D8%A7%D8%B3%D8%AA_%D9%85%D8%B9_%D8%B1%D9%88%D8%B2%DA%AF%D8%A7%D8%B1_%D9%86%D8%A7%D8%B4%D8%B1_%D9%85%DB%8C%DA%AF%D9%84_%D8%AF_%D8%B3%D8%B1%D9%88%D8%A7%D9%86%D8%AA%D8%B3_%D9%86%D9%88%DB%8C%D8%B3%D9%86%D8%AF%D9%87_%D9%BE%DB%8C%D8%B4_%D9%86%D9%85%D8%A7%DB%8C%D8%B4_%D9%88_%D8%AE%D8%B1%DB%8C%D8%AF_%D9%BE%DB%8C%D8%B4_%D9%86%D9%85%D8%A7%DB%8C%D8%B4_%D9%88_%D8%AE%D8%B1%DB%8C%D8%AF_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA_%D8%AA%D8%B1%D8%AC%D9%85%D9%87_%D8%B0%D8%A8%DB%8C%D8%AD_%D8%A7%D9%84%D9%84%D9%87_%D9%85%D9%86%D8%B5%D9%88%D8%B1%DB%8C\"><\/span>\n\t                                            <a href=\"https:\/\/faraketab.ir\/book\/16593\" > \u062f\u0648\u0646 \u06a9\u06cc\u0634\u0648\u062a (\u062c\u0644\u062f \u0627\u0648\u0644)<\/a >        \n\t                                        <\/h3 >\n\t                                        <div class=\"description\" > \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c \u0627\u062b\u0631 \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633 \u0648 \u0628\u0627 \u062a\u0631\u062c\u0645\u0647 \u06a9\u06cc\u0648\u0645\u0631\u062b \u067e\u0627\u0631\u0633\u0627\u06cc \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631\u0622\u0645\u062f\u0647 \u0648 \u062f\u0631 \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0631\u0648\u0632\u06af\u0627\u0631 \u0628\u0647 \u0646\u0634\u0631 \u0648 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0639\u0644\u0627\u0642\u0647 \u0645\u0646\u062f\u0627\u0646 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a.\n\n\u0645\u0639...<\/div >\n\t                                    <\/div>\n\t                                    <div class=\"caption\" ><div class=\"user\">\n            <img decoding=\"async\" loading=\"lazy\"\n                 src=\"https:\/\/www.faraketab.ir\/blog\/wp-content\/themes\/alizadeh\/images\/cover.png\"\n                 class=\"user__avatar\" alt=\"\"\/>\n            <div class=\"user__info\">\n                <div class=\"user__name\">\u0631\u0648\u0632\u06af\u0627\u0631<\/div>\n                <div class=\"user__job\">\u0646\u0627\u0634\u0631<\/div>\n            <\/div>\n        <\/div><div class=\"user\">\n            <img decoding=\"async\" loading=\"lazy\"\n                 src=\"https:\/\/www.faraketab.ir\/blog\/wp-content\/themes\/alizadeh\/images\/cover.png\"\n                 class=\"user__avatar\" alt=\"\"\/>\n            <div class=\"user__info\">\n                <div class=\"user__name\">\u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633<\/div>\n                <div class=\"user__job\">\u0646\u0648\u06cc\u0633\u0646\u062f\u0647<\/div>\n            <\/div>\n        <\/div><\/div >\n\t                                    <a href=\"https:\/\/faraketab.ir\/book\/16593\" class=\"btn\">\u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0634 \u0648 \u062e\u0631\u06cc\u062f<\/a>\n\t                                <\/div>\n\t                                 <a href=\"https:\/\/faraketab.ir\/book\/16593\" class=\"btn\">\u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0634 \u0648 \u062e\u0631\u06cc\u062f<\/a>\n\t                            <\/div>\n\t                        <\/div>\n<h3>\u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a \u062a\u0631\u062c\u0645\u0647\u00a0\u0630\u0628\u06cc\u062d \u0627\u0644\u0644\u0647 \u0645\u0646\u0635\u0648\u0631\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><a href=\"https:\/\/www.faraketab.ir\/book\/179050-%D8%AF%D9%86-%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\">\u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/a> \u062a\u0631\u062c\u0645\u0647\u00a0\u0630\u0628\u06cc\u062d \u0627\u0644\u0644\u0647 \u0645\u0646\u0635\u0648\u0631\u06cc \u06a9\u0647 \u062a\u0648\u0633\u0637 \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0646\u06af\u0627\u0647 \u0631\u0648\u0627\u0646\u0647 \u0628\u0627\u0632\u0627\u0631 \u06a9\u062a\u0627\u0628 \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0628\u0635\u0648\u0631\u062a \u0686\u0627\u067e\u06cc \u0627\u0632 \u0627\u067e\u0644\u06cc\u06a9\u06cc\u0634\u0646 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0642\u0627\u0628\u0644 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<div class=\"special-product\">\n\t                            <div class=\"special-product__content\">\n\t                                <a class=\"special-product__thumbnail\" href=\"https:\/\/faraketab.ir\/book\/179050\" title=\"\u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\">\t                                   \n\t                                    <div class=\"special-product__discount\" >15<i class=\"far fa-percent\" ><\/i > \u062a\u062e\u0641\u06cc\u0641<\/div >\n\t                                    <picture >\n\t                                        <source type = \"image\/avif\" srcset = \"https:\/\/file1.cdn.faraketab.ir\/content_file\/content-1-179050-838140\/%D8%AF%D9%86%20%DA%A9%DB%8C%D8%B4%D9%88%D8%AA.jpg\" >\n\t                                        <source type = \"image\/webp\" srcset = \"https:\/\/file1.cdn.faraketab.ir\/content_file\/content-1-179050-838140\/%D8%AF%D9%86%20%DA%A9%DB%8C%D8%B4%D9%88%D8%AA.jpg\" >\n\t                                        <img class=\"product-thumbnail\" srcset = \"https:\/\/file1.cdn.faraketab.ir\/content_file\/content-1-179050-838140\/%D8%AF%D9%86%20%DA%A9%DB%8C%D8%B4%D9%88%D8%AA.jpg\" alt = \"\" title = \"\" >\n\t                                    <\/picture >\n\t                                    <div class=\"detail\" >\n\t                                        <div class=\"rate\"><i class='fa fa-star '><\/i><i class='fa fa-star '><\/i><i class='fa fa-star '><\/i><i class='fa fa-star '><\/i><i class='fa fa-star '><\/i><\/div >\n\t                                        <div class=\"type\" >\n\t                                           <i class='far fa-file '><\/i>\n                    <i class='far fa-headphones '><\/i>\n                    <i class='far fa-book active'><\/i>\n\t                                        <\/div >\n\t                                    <\/div >\n\t                                <\/a>\n\t                                <div class=\"special-product__details\" >\n\t                                    <div>\n\t                                        <h3 class=\"title\" >\n\t                                            <a href=\"https:\/\/faraketab.ir\/book\/179050\" > \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<\/a >        \n\t                                        <\/h3 >\n\t                                        <div class=\"description\" > ...<\/div >\n\t                                    <\/div>\n\t                                    <div class=\"caption\" ><div class=\"user\">\n            <img decoding=\"async\" loading=\"lazy\"\n                 src=\"https:\/\/www.faraketab.ir\/blog\/wp-content\/themes\/alizadeh\/images\/cover.png\"\n                 class=\"user__avatar\" alt=\"\"\/>\n            <div class=\"user__info\">\n                <div class=\"user__name\">\u0646\u06af\u0627\u0647<\/div>\n                <div class=\"user__job\">\u0646\u0627\u0634\u0631<\/div>\n            <\/div>\n        <\/div><div class=\"user\">\n            <img decoding=\"async\" loading=\"lazy\"\n                 src=\"https:\/\/www.faraketab.ir\/blog\/wp-content\/themes\/alizadeh\/images\/cover.png\"\n                 class=\"user__avatar\" alt=\"\"\/>\n            <div class=\"user__info\">\n                <div class=\"user__name\">\u0645\u06cc\u06af\u0648\u0626\u0644 \u062f\u0648 \u0633\u0631\u0648\u0627\u0646\u062a\u0633<\/div>\n                <div class=\"user__job\">\u0646\u0648\u06cc\u0633\u0646\u062f\u0647<\/div>\n            <\/div>\n        <\/div><\/div >\n\t                                    <a href=\"https:\/\/faraketab.ir\/book\/179050\" class=\"btn\">\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628<\/a>\n\t                                <\/div>\n\t                                 <a href=\"https:\/\/faraketab.ir\/book\/179050\" class=\"btn\">\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628<\/a>\n\t                            <\/div>\n\t                        <\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D9%84%D8%A7%D8%AA_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\"><\/span>\u062c\u0645\u0644\u0627\u062a \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0642\u0633\u0645\u062a \u0686\u0646\u062f \u062c\u0645\u0644\u0647 \u0627\u0632 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a \u0631\u0627 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0645\u062e\u0627\u0637\u0628\u0627\u0646 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u06a9\u0646\u06cc\u0645:<\/p>\n<p>\u0646\u0647 \u0648\u0627\u0642\u0639\u06cc\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u062a\u0627\u0631\u06cc\u062e \u06cc\u0627 \u062c\u0627\u06cc \u062f\u06cc\u06af\u0631\u06cc \u0646\u062e\u0648\u0627\u0646\u062f\u0647 \u0627\u0645\u060c \u0686\u0648\u0646 \u0646\u0647 \u062e\u0648\u0627\u0646\u062f\u0646 \u0628\u0644\u062f\u0645 \u0648 \u0646\u0647 \u0646\u0648\u0634\u062a\u0646. \u0648\u0644\u06cc \u0628\u0647 \u062c\u0631\u0627\u062a \u0645\u06cc \u062a\u0648\u0627\u0646\u0645 \u0628\u06af\u0648\u06cc\u0645 \u06a9\u0647 \u062a\u0627 \u06a9\u0646\u0648\u0646 \u062f\u0631 \u062e\u062f\u0645\u062a \u06a9\u0633\u06cc \u0646\u0628\u0648\u062f\u0647 \u0627\u0645 \u06a9\u0647 \u0634\u062c\u0627\u0639 \u062a\u0631 \u0627\u0632 \u0634\u0645\u0627 \u0628\u0627\u0634\u062f. \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0645 \u0627\u06cc\u0646 \u0634\u062c\u0627\u0639\u062a \u0645\u0648\u062c\u0628 \u06af\u0631\u0641\u062a\u0627\u0631\u06cc \u0648 \u0645\u0631\u06af \u0646\u0634\u0648\u062f.<br \/>\n&#8230;<br \/>\n\u0633\u0627\u06a9\u062a \u0628\u0627\u0634! \u0647\u0631\u06af\u0632 \u062f\u0631 \u062c\u0627\u06cc\u06cc \u062e\u0648\u0627\u0646\u062f\u0647 \u06cc\u0627 \u0634\u0646\u06cc\u062f\u0647 \u0627\u06cc \u067e\u0647\u0644\u0648\u0627\u0646\u06cc \u062f\u0646\u06cc\u0627\u06af\u0631\u062f \u0631\u0627 \u062d\u062a\u06cc \u0627\u06af\u0631 \u0645\u0631\u062a\u06a9\u0628 \u0642\u062a\u0644 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u0628\u0647 \u062f\u0627\u062f\u06af\u0627\u0647 \u0628\u0628\u0631\u0646\u062f\u061f<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AF%D8%A7%D9%86%D9%84%D9%88%D8%AF_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D9%86_%DA%A9%DB%8C%D8%B4%D9%88%D8%AA\"><\/span>\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0646\u0633\u062e\u0647 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0\u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u0646\u06cc\u062f \u0648 \u0633\u067e\u0633 \u0622\u0646 \u0631\u0627 \u062f\u0631 \u06a9\u062a\u0627\u0628\u062e\u0648\u0627\u0646 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0645\u0648\u0631\u062f \u0645\u0637\u0627\u0644\u0639\u0647 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>\u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c \u0627\u062b\u0631 \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633 \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631\u0622\u0645\u062f\u0647 \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u062b\u0631 \u0627\u0632 \u06a9\u064f\u0647\u0646\u200c\u062a\u0631\u06cc\u0646\u00a0\u0631\u0645\u0627\u0646\u200c\u0647\u0627 \u062f\u0631 \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0627\u0631\u0648\u067e\u0627\u06cc\u06cc\u00a0\u0627\u0633\u062a.\u00a0\u0633\u0631\u0648\u0627\u0646\u062a\u0633\u060c \u0628\u062e\u0634 \u0627\u0648\u0644\u00a0\u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a \u0631\u0627 \u062f\u0631 \u0632\u0646\u062f\u0627\u0646 \u0646\u0648\u0634\u062a\u061b \u06a9\u0647 \u0628\u062e\u0634 \u0627\u0648\u0644 \u0646\u062e\u0633\u062a\u06cc\u0646 \u0628\u0627\u0631 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f6\u06f0\u06f5 \u0645\u06cc\u0644\u0627\u062f\u06cc \u0648 \u0628\u062e\u0634 \u062f\u0648\u0645 \u0646\u06cc\u0632 \u062f\u0631 \u06f1\u06f6\u06f1\u06f5 \u0645\u06cc\u0644\u0627\u062f\u06cc \u062f\u0631 \u0645\u0627\u062f\u0631\u06cc\u062f\u060c \u0686\u0627\u067e \u0648 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f. \u0646\u0633\u062e\u0647 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":10176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-10173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-introduction-of-authors-and-translators"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0<\/title>\n<meta name=\"description\" content=\"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c \u0627\u062b\u0631 \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633 \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631\u0622\u0645\u062f\u0647 \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u062b\u0631 \u0627\u0632 \u06a9\u064f\u0647\u0646\u200c\u062a\u0631\u06cc\u0646\u00a0\u0631\u0645\u0627\u0646\u200c\u0647\u0627 \u062f\u0631 \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0627\u0631\u0648\u067e\u0627\u06cc\u06cc\u00a0\u0627\u0633\u062a.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.faraketab.ir\/blog\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0\" \/>\n<meta property=\"og:description\" content=\"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c \u0627\u062b\u0631 \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633 \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631\u0622\u0645\u062f\u0647 \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u062b\u0631 \u0627\u0632 \u06a9\u064f\u0647\u0646\u200c\u062a\u0631\u06cc\u0646\u00a0\u0631\u0645\u0627\u0646\u200c\u0647\u0627 \u062f\u0631 \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0627\u0631\u0648\u067e\u0627\u06cc\u06cc\u00a0\u0627\u0633\u062a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.faraketab.ir\/blog\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-09T07:40:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2024\/08\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1410\" \/>\n\t<meta property=\"og:image:height\" content=\"793\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0633\u0645\u0627\u0646\u0647 \u062e\u0648\u0634 \u0627\u0646\u06af\u0634\u062a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0633\u0645\u0627\u0646\u0647 \u062e\u0648\u0634 \u0627\u0646\u06af\u0634\u062a\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/\"},\"author\":{\"name\":\"\u0633\u0645\u0627\u0646\u0647 \u062e\u0648\u0634 \u0627\u0646\u06af\u0634\u062a\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#\\\/schema\\\/person\\\/f2b40c2c692534c5cc1cebf550191ab6\"},\"headline\":\"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0\",\"datePublished\":\"2024-09-09T07:40:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/\"},\"wordCount\":4,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a-.jpg\",\"articleSection\":[\"\u0645\u0639\u0631\u0641\u06cc \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646 \u0648 \u0645\u062a\u0631\u062c\u0645\u0627\u0646\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/\",\"name\":\"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a-.jpg\",\"datePublished\":\"2024-09-09T07:40:40+00:00\",\"description\":\"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c \u0627\u062b\u0631 \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633 \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631\u0622\u0645\u062f\u0647 \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u062b\u0631 \u0627\u0632 \u06a9\u064f\u0647\u0646\u200c\u062a\u0631\u06cc\u0646\u00a0\u0631\u0645\u0627\u0646\u200c\u0647\u0627 \u062f\u0631 \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0627\u0631\u0648\u067e\u0627\u06cc\u06cc\u00a0\u0627\u0633\u062a.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a-.jpg\",\"width\":1410,\"height\":793,\"caption\":\"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/\",\"name\":\"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#organization\",\"name\":\"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-faraketab.png\",\"contentUrl\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-faraketab.png\",\"width\":420,\"height\":432,\"caption\":\"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628\"},\"image\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#\\\/schema\\\/person\\\/f2b40c2c692534c5cc1cebf550191ab6\",\"name\":\"\u0633\u0645\u0627\u0646\u0647 \u062e\u0648\u0634 \u0627\u0646\u06af\u0634\u062a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1edba782a8679a8ee4999b8b838e729b4daab846f7585d63b6c3487639e17ce6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1edba782a8679a8ee4999b8b838e729b4daab846f7585d63b6c3487639e17ce6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1edba782a8679a8ee4999b8b838e729b4daab846f7585d63b6c3487639e17ce6?s=96&d=mm&r=g\",\"caption\":\"\u0633\u0645\u0627\u0646\u0647 \u062e\u0648\u0634 \u0627\u0646\u06af\u0634\u062a\"},\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/author\\\/samanekhosh\\\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0","description":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c \u0627\u062b\u0631 \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633 \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631\u0622\u0645\u062f\u0647 \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u062b\u0631 \u0627\u0632 \u06a9\u064f\u0647\u0646\u200c\u062a\u0631\u06cc\u0646\u00a0\u0631\u0645\u0627\u0646\u200c\u0647\u0627 \u062f\u0631 \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0627\u0631\u0648\u067e\u0627\u06cc\u06cc\u00a0\u0627\u0633\u062a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.faraketab.ir\/blog\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0","og_description":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c \u0627\u062b\u0631 \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633 \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631\u0622\u0645\u062f\u0647 \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u062b\u0631 \u0627\u0632 \u06a9\u064f\u0647\u0646\u200c\u062a\u0631\u06cc\u0646\u00a0\u0631\u0645\u0627\u0646\u200c\u0647\u0627 \u062f\u0631 \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0627\u0631\u0648\u067e\u0627\u06cc\u06cc\u00a0\u0627\u0633\u062a.","og_url":"https:\/\/www.faraketab.ir\/blog\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a\/","og_site_name":"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628","article_published_time":"2024-09-09T07:40:40+00:00","og_image":[{"width":1410,"height":793,"url":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2024\/08\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a-.jpg","type":"image\/jpeg"}],"author":"\u0633\u0645\u0627\u0646\u0647 \u062e\u0648\u0634 \u0627\u0646\u06af\u0634\u062a","twitter_card":"summary_large_image","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"\u0633\u0645\u0627\u0646\u0647 \u062e\u0648\u0634 \u0627\u0646\u06af\u0634\u062a","\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646":"4 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#article","isPartOf":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/"},"author":{"name":"\u0633\u0645\u0627\u0646\u0647 \u062e\u0648\u0634 \u0627\u0646\u06af\u0634\u062a","@id":"https:\/\/www.faraketab.ir\/blog\/#\/schema\/person\/f2b40c2c692534c5cc1cebf550191ab6"},"headline":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0","datePublished":"2024-09-09T07:40:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/"},"wordCount":4,"commentCount":0,"publisher":{"@id":"https:\/\/www.faraketab.ir\/blog\/#organization"},"image":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2024\/08\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a-.jpg","articleSection":["\u0645\u0639\u0631\u0641\u06cc \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646 \u0648 \u0645\u062a\u0631\u062c\u0645\u0627\u0646"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/","url":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/","name":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0","isPartOf":{"@id":"https:\/\/www.faraketab.ir\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#primaryimage"},"image":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2024\/08\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a-.jpg","datePublished":"2024-09-09T07:40:40+00:00","description":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u060c \u0627\u062b\u0631 \u0645\u06cc\u06af\u0644 \u062f \u0633\u0631\u0648\u0627\u0646\u062a\u0633 \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631\u0622\u0645\u062f\u0647 \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u062b\u0631 \u0627\u0632 \u06a9\u064f\u0647\u0646\u200c\u062a\u0631\u06cc\u0646\u00a0\u0631\u0645\u0627\u0646\u200c\u0647\u0627 \u062f\u0631 \u0632\u0628\u0627\u0646\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0627\u0631\u0648\u067e\u0627\u06cc\u06cc\u00a0\u0627\u0633\u062a.","breadcrumb":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#primaryimage","url":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2024\/08\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a-.jpg","contentUrl":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2024\/08\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u062a\u0631\u062c\u0645\u0647-\u06a9\u062a\u0627\u0628-\u062f\u0646-\u06a9\u06cc\u0634\u0648\u062a-.jpg","width":1410,"height":793,"caption":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.faraketab.ir\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%af%d9%86-%da%a9%db%8c%d8%b4%d9%88%d8%aa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/www.faraketab.ir\/blog\/"},{"@type":"ListItem","position":2,"name":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u062c\u0645\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0646 \u06a9\u06cc\u0634\u0648\u062a\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.faraketab.ir\/blog\/#website","url":"https:\/\/www.faraketab.ir\/blog\/","name":"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628","description":"","publisher":{"@id":"https:\/\/www.faraketab.ir\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.faraketab.ir\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/www.faraketab.ir\/blog\/#organization","name":"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628","url":"https:\/\/www.faraketab.ir\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/www.faraketab.ir\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2025\/06\/logo-faraketab.png","contentUrl":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2025\/06\/logo-faraketab.png","width":420,"height":432,"caption":"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628"},"image":{"@id":"https:\/\/www.faraketab.ir\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.faraketab.ir\/blog\/#\/schema\/person\/f2b40c2c692534c5cc1cebf550191ab6","name":"\u0633\u0645\u0627\u0646\u0647 \u062e\u0648\u0634 \u0627\u0646\u06af\u0634\u062a","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/secure.gravatar.com\/avatar\/1edba782a8679a8ee4999b8b838e729b4daab846f7585d63b6c3487639e17ce6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1edba782a8679a8ee4999b8b838e729b4daab846f7585d63b6c3487639e17ce6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1edba782a8679a8ee4999b8b838e729b4daab846f7585d63b6c3487639e17ce6?s=96&d=mm&r=g","caption":"\u0633\u0645\u0627\u0646\u0647 \u062e\u0648\u0634 \u0627\u0646\u06af\u0634\u062a"},"url":"https:\/\/www.faraketab.ir\/blog\/author\/samanekhosh\/"},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/posts\/10173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/comments?post=10173"}],"version-history":[{"count":4,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/posts\/10173\/revisions"}],"predecessor-version":[{"id":10314,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/posts\/10173\/revisions\/10314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/media\/10176"}],"wp:attachment":[{"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/media?parent=10173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/categories?post=10173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/tags?post=10173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}