{"id":3629,"date":"2023-05-14T13:53:05","date_gmt":"2023-05-14T10:23:05","guid":{"rendered":"https:\/\/www.faraketab.ir\/blog\/?p=3629"},"modified":"2024-07-18T14:47:17","modified_gmt":"2024-07-18T11:17:17","slug":"%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2","status":"publish","type":"post","link":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/","title":{"rendered":"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2"},"content":{"rendered":"<p>\u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u06f2 \u06a9\u0627\u0631\u06cc \u0627\u0632 \u06af\u0631\u0648\u0647 \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646 \u0627\u0646\u062c\u0645\u0646 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u0645\u06cc\u200c\u0628\u0627\u0634\u062f \u0648 <strong><a href=\"https:\/\/www.faraketab.ir\/person\/40015-%D8%A7%D9%86%D8%AA%D8%B4%D8%A7%D8%B1%D8%A7%D8%AA-%D8%B4%D9%87%DB%8C%D8%AF-%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85-%D9%87%D8%A7%D8%AF%DB%8C\">\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0634\u0647\u06cc\u062f \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc<\/a><\/strong> \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0686\u0627\u067e \u0631\u0633\u0627\u0646\u062f\u0647 \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 <strong>\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2<\/strong>\u00a0\u0631\u0627 \u062a\u0642\u062f\u06cc\u0645\u062a\u0627\u0646 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%87%D8%A7%D8%AF%DB%8C\" >\u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#%D8%B2%D9%86%D8%AF%DA%AF%DB%8C%D9%86%D8%A7%D9%85%D9%87_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%87%D8%A7%D8%AF%DB%8C\" >\u0632\u0646\u062f\u06af\u06cc\u0646\u0627\u0645\u0647 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#%D9%88%D8%B5%DB%8C%D8%AA_%D9%86%D8%A7%D9%85%D9%87_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%87%D8%A7%D8%AF%DB%8C\" >\u0648\u0635\u06cc\u062a \u0646\u0627\u0645\u0647 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%DB%B2\" >\u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u06f2<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#%D8%AE%D9%84%D8%A7%D8%B5%D9%87_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_2\" >\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%AC%D9%84%D8%AF_%D8%AF%D9%88%D9%85_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_2_%DA%A9%D8%A7%D8%B1%DB%8C_%D8%A7%D8%B2_%DA%AF%D8%B1%D9%88%D9%87_%D9%86%D9%88%DB%8C%D8%B3%D9%86%D8%AF%DA%AF%D8%A7%D9%86_%D8%A7%D9%86%D8%AC%D9%85%D9%86_%D8%B4%D9%87%DB%8C%D8%AF_%D9%87%D8%A7%D8%AF%DB%8C_%D9%85%DB%8C_%D8%A8%D8%A7%D8%B4%D8%AF_%D9%88_%D8%A7%D9%86%D8%AA%D8%B4%D8%A7%D8%B1%D8%A7%D8%AA_%D8%B4%D9%87%DB%8C%D8%AF_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%87%D8%A7%D8%AF%DB%8C_%D8%A2%D9%86_%D8%B1%D8%A7_%D8%A8%D9%87_%DA%86%D8%A7%D9%BE_%D8%B1%D8%B3%D8%A7%D9%86%D8%AF%D9%87_%D8%A7%D8%B3%D8%AA_%D8%AE%D8%A7%D8%B7%D8%B1%D8%A7%D8%AA_%D8%A7%DB%8C%D9%86_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D8%B1_%D8%A7%D8%AF%D8%A7%D9%85%D9%87_%DA%A9_%DA%AF%D8%B1%D9%88%D9%87_%D9%86%D9%88%DB%8C%D8%B3%D9%86%D8%AF%DA%AF%D8%A7%D9%86_%D9%86%D9%88%DB%8C%D8%B3%D9%86%D8%AF%D9%87_%D8%A7%D9%86%D8%AA%D8%B4%D8%A7%D8%B1%D8%A7%D8%AA_%D8%B4%D9%87%DB%8C%D8%AF_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%87%D8%A7%D8%AF%DB%8C_%D9%86%D8%A7%D8%B4%D8%B1_%D9%BE%DB%8C%D8%B4_%D9%86%D9%85%D8%A7%DB%8C%D8%B4_%D9%88_%D8%AE%D8%B1%DB%8C%D8%AF_%D9%BE%DB%8C%D8%B4_%D9%86%D9%85%D8%A7%DB%8C%D8%B4_%D9%88_%D8%AE%D8%B1%DB%8C%D8%AF_%D8%A8%D8%B1%D8%B4%DB%8C_%D8%A7%D8%B2_%D9%85%D8%AA%D9%86_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%DB%B2_%D9%85%D9%86_%D8%A8%D8%A7_%D8%B4%D9%87%D8%AF%D8%A7%DB%8C_%D8%B2%DB%8C%D8%A7%D8%AF%DB%8C_%D8%AD%D8%B4%D8%B1_%D9%88_%D9%86%D8%B4%D8%B1_%D8%AF%D8%A7%D8%B4%D8%AA%D9%85_%D8%A7%D9%85%D8%A7_%D8%B4%D8%A8%DB%8C%D9%87_%D8%B4%D8%AE%D8%B5%DB%8C%D8%AA_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%B1%D8%A7_%D8%AF%D8%B1_%DA%A9%D9%85%D8%AA%D8%B1_%DA%A9%D8%B3%DB%8C_%D8%AF%DB%8C%D8%AF%D9%85_%D8%A8%D8%B1%D8%AE%DB%8C_%D8%A7%D9%81%D8%B1%D8%A7%D8%AF_%D8%A8%D9%88%D8%AF%D9%86%D8%AF_%DA%A9%D9%87_%D8%A8%D8%B9%D8%B6%DB%8C_%D8%A7%D8%B2_%D8%AE%D8%B5%D9%88%D8%B5%DB%8C%D8%A7%D8%AA_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%B1%D8%A7_%D8%AF%D8%A7%D8%B4%D8%AA%D9%86%D8%AF%D8%8C_%D8%A7%D9%85%D8%A7_%D8%A7%DB%8C%D9%86%DA%A9%D9%87_%DA%A9%D8%B3%DB%8C_%D9%85%D8%A7%D9%86%D9%86%D8%AF_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85%D8%8C_%D8%A7%DB%8C%D9%86_%D9%82%D8%AF%D8%B1_%D8%AC%D8%A7%D9%85%D8%B9_%D8%A7%D9%84%D8%A7%D8%B7%D8%B1%D8%A7%D9%81_%D8%A8%D8%A7%D8%B4%D8%AF_%D8%B1%D8%A7_%D9%86%D8%AF%DB%8C%D8%AF%D9%85_%D9%85%D8%AD%D8%A8%D8%AA_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%B4%D8%A7%D9%85%D9%84_%D8%AD%D8%A7%D9%84_%D9%87%D9%85%D9%87_%D9%85%DB%8C_%D8%B4%D8%AF_%D8%A7%D8%B2_%D8%A7%D8%B3%D8%B1%D8%A7%DB%8C_%D8%B9%D8%B1%D8%A7%D9%82%DB%8C_%D8%AA%D8%A7_%D8%A8%D8%B1%D8%AE%DB%8C_%D8%B1%D8%B2%D9%85%D9%86%D8%AF%DA%AF%D8%A7%D9%86_%DA%A9%D9%87_%D8%A7%D8%B2_%D9%86%D9%82%D8%A7%D8%B7_%D8%AF%D9%88%D8%B1_%D8%AF%D8%B3%D8%AA_%D8%A7%DB%8C%D8%B1%D8%A7%D9%86_%D8%A2%D9%85%D8%AF%D9%87_%D8%A8%D9%88%D8%AF%D9%86%D8%AF_%D8%A7%DB%8C%D9%86_%D8%B9%D8%B4%D9%82_%D9%88_%D9%85%D8%AD%D8%A8%D8%AA%D8%8C_%D8%B8%D8%A7%D9%87%D8%B1%DB%8C_%D9%87%D9%85_%D9%86%D8%A8%D9%88%D8%AF_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%A8%D8%A7_%D8%B9%D8%B4%D9%82_%D9%88_%D8%B9%D9%84%D8%A7%D9%82%D9%87_%D8%A8%D9%87_%D8%AF%DB%8C%DA%AF%D8%B1%D8%A7%D9%86_%D8%AE%D8%AF%D9%85%D8%AA_%D9%85%DB%8C_%DA%A9%D8%B1%D8%AF_%D8%A7%DB%8C%D9%86%DA%A9%D9%87_%D8%A8%D8%A8%DB%8C%D9%86%D8%AF_%DB%8C%DA%A9_%D8%A8%D9%86%D8%AF%D9%87_%D8%AE%D8%AF%D8%A7_%D8%A7%D8%B0%DB%8C%D8%AA_%D9%85%DB%8C_%D8%B4%D9%88%D8%AF%D8%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D9%88_%D8%A8%D8%B3%DB%8C%D8%A7%D8%B1_%D8%B3%D8%AE%D8%AA_%D8%A8%D9%88%D8%AF_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%85%D8%B3%D8%A6%D9%88%D9%84%DB%8C%D8%AA_%D9%88_%D9%81%D8%B1%D9%85%D8%A7%D9%86%D8%AF%D9%87%DB%8C_%D9%82%D8%A8%D9%88%D9%84_%D9%86%D9%85%DB%8C_%DA%A9%D8%B1%D8%AF_%D8%B4%D8%A7%DB%8C%D8%AF_%DB%8C%DA%A9%DB%8C_%D8%A7%D8%B2_%D8%AF%D9%84%D8%A7%DB%8C%D9%84%D8%B4_%D8%A7%DB%8C%D9%86_%D8%A8%D9%88%D8%AF_%DA%A9%D9%87_%D8%AF%D8%B1_%D8%B2%D9%85%D8%A7%D9%86_%D9%85%D8%B3%D8%A6%D9%88%D9%84%DB%8C%D8%AA%D8%8C_%D8%A7%D9%85%DA%A9%D8%A7%D9%86_%D8%AF%D8%A7%D8%B1%D8%AF_%D8%A7%D9%86%D8%B3%D8%A7%D9%86_%D8%AA%D8%B5%D9%85%DB%8C%D9%85_%D8%AF%D8%B1%D8%B3%D8%AA%DB%8C_%D9%86%DA%AF%DB%8C%D8%B1%D8%AF_%D9%88_%D9%87%D9%85%DB%8C%D9%86_%D8%A8%D8%A7%D8%B9%D8%AB_%D8%B1%D9%86%D8%AC%D8%B4_%D8%A7%D8%B7%D8%B1%D8%A7%D9%81%DB%8C%D8%A7%D9%86_%D8%B4%D9%88%D8%AF_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%87%D9%85%DB%8C%D9%86_%D9%87%D9%85%DB%8C%D8%B4%D9%87_%D9%85%DB%8C_%DA%AF%D9%81%D8%AA_%DB%8C%DA%A9_%D9%86%D9%81%D8%B1_%D8%A7%D8%B2_%D8%AF%D9%88%D8%B3%D8%AA%D8%A7%D9%86%D8%8C_%D9%85%D8%B3%D8%A6%D9%88%D9%84%DB%8C%D8%AA_%D8%B1%D8%A7_%D9%82%D8%A8%D9%88%D9%84_%DA%A9%D9%86%D8%AF_%D9%88_%D9%85%D8%A7_%D8%A8%D8%A7_%D8%AA%D9%85%D8%A7%D9%85_%D8%AA%D9%88%D8%A7%D9%86_%D8%AF%D8%B1_%DA%A9%D9%86%D8%A7%D8%B1%D8%B4_%D9%87%D8%B3%D8%AA%DB%8C%D9%85_%DA%A9%D9%87_%D8%AF%DB%8C%DA%AF%D8%B1_%D8%A7%DB%8C%D9%86%DA%A9%D9%87_%D9%82%D9%84%D8%A8_%D8%B1%D8%A6%D9%88%D9%81_%D9%88_%D9%85%D9%87%D8%B1%D8%A8%D8%A7%D9%86_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%A8%D9%87_%D8%AD%DB%8C%D9%88%D8%A7%D9%86%D8%A7%D8%AA_%D9%87%D9%85_%D9%85%D8%AD%D8%A8%D8%AA_%D8%AF%D8%A7%D8%B4%D8%AA_%DA%A9%D9%87_%D9%85%DB%8C_%D8%AA%D9%88%D8%A7%D9%86%D8%B3%D8%AA_%D8%A8%D8%A8%DB%8C%D9%86%D8%AF_%DA%A9%D9%87_%DB%8C%DA%A9_%D8%AD%DB%8C%D9%88%D8%A7%D9%86_%D8%A7%D8%B0%DB%8C%D8%AA_%D9%85%DB%8C_%D8%B4%D9%88%D8%AF_%D8%A8%D8%AE%D8%B4_%D8%B1%D9%88%D8%B2_%D9%82%D8%B1%D8%A7%D8%B1_%D8%B4%D8%AF_%DA%A9%D9%87_%D8%A8%D8%A7_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85%D8%8C_%D8%A7%D8%B2_%DA%AF%DB%8C%D9%84%D8%A7%D9%86_%D8%BA%D8%B1%D8%A8_%D8%A8%D9%87_%DA%A9%D8%B1%D9%85%D8%A7%D9%86%D8%B4%D8%A7%D9%87_%D9%88_%D8%A7%D8%B2_%D8%A2%D9%86%D8%AC%D8%A7_%D8%A8%D9%87_%D8%AA%D9%87%D8%B1%D8%A7%D9%86_%D8%AA%DB%8C%D9%85_%D8%B3%D9%88%D8%A7%D8%B1_%D9%85%DB%8C%D9%86%DB%8C_%D8%A8%D9%88%D8%B3_%D9%88_%D8%B1%D8%A7%D9%87%DB%8C_%DA%A9%D8%B1%D9%85%D8%A7%D9%86%D8%B4%D8%A7%D9%87_%D8%B4%D8%AF%DB%8C%D9%85_%D8%AF%D8%A7%D9%86%D9%84%D9%88%D8%AF_%D8%B1%D8%A7%DB%8C%DA%AF%D8%A7%D9%86_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_1_%D9%85%D8%AF%D8%AA%DB%8C_%D9%BE%D8%B3_%D8%A7%D8%B2_%D8%A7%D9%86%D8%AA%D8%B4%D8%A7%D8%B1_%D8%AC%D9%84%D8%AF_%D8%A7%D9%88%D9%84_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85%D8%8C_%D9%86%D8%A7%D8%B4%D8%B1_%D8%A7%DB%8C%D9%86_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%A2%D9%86_%D8%B1%D8%A7_%D8%A8%D9%87_%D8%B5%D9%88%D8%B1%D8%AA_%D8%B1%D8%A7%DB%8C%DA%AF%D8%A7%D9%86_%D8%AF%D8%B1_%D9%81%D8%B1%D8%A7%DA%A9%D8%AA%D8%A7%D8%A8_%D9%85%D9%86%D8%AA%D8%B4%D8%B1_%DA%A9%D8%B1%D8%AF%D9%87_%D8%A7%D8%B3%D8%AA_%D9%88_%D8%AF%D8%B1_%D8%A2%D8%AF%D8%B1%D8%B3_%D8%B0%DB%8C%D9%84_%D8%AF%D8%B1_%D8%AF%D8%B3%D8%AA%D8%B1%D8%B3_%D8%B4%D9%85%D8%A7%D8%B3%D8%AA_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85\" >\u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 (\u062c\u0644\u062f \u062f\u0648\u0645)        \n\t                                        \n\t                                         \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2 \u06a9\u0627\u0631\u06cc \u0627\u0632 \u06af\u0631\u0648\u0647 \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646 \u0627\u0646\u062c\u0645\u0646 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f \u0648 \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0634\u0647\u06cc\u062f \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0686\u0627\u067e \u0631\u0633\u0627\u0646\u062f\u0647 \u0627\u0633\u062a. \u062e\u0627\u0637\u0631\u0627\u062a \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u06a9...\n\t                                    \n\t                                    \n            \n            \n                \u06af\u0631\u0648\u0647 \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646\n                \u0646\u0648\u06cc\u0633\u0646\u062f\u0647\n            \n        \n            \n            \n                \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0634\u0647\u06cc\u062f \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc\n                \u0646\u0627\u0634\u0631\n            \n        \n\t                                    \u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0634 \u0648 \u062e\u0631\u06cc\u062f\n\t                                \n\t                                 \u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0634 \u0648 \u062e\u0631\u06cc\u062f\n\t                            \n\t                        \n\u0628\u0631\u0634\u06cc \u0627\u0632 \u0645\u062a\u0646 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u06f2\n\u0645\u0646 \u0628\u0627 \u0634\u0647\u062f\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u062d\u0634\u0631 \u0648 \u0646\u0634\u0631 \u062f\u0627\u0634\u062a\u0645. \u0627\u0645\u0627 \u0634\u0628\u06cc\u0647 \u0634\u062e\u0635\u06cc\u062a \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0631\u0627 \u062f\u0631 \u06a9\u0645\u062a\u0631 \u06a9\u0633\u06cc \u062f\u06cc\u062f\u0645. \u0628\u0631\u062e\u06cc \u0627\u0641\u0631\u0627\u062f \u0628\u0648\u062f\u0646\u062f \u06a9\u0647 \u0628\u0639\u0636\u06cc \u0627\u0632 \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0631\u0627 \u062f\u0627\u0634\u062a\u0646\u062f\u060c \u0627\u0645\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u06a9\u0633\u06cc \u0645\u0627\u0646\u0646\u062f \u0627\u0628\u0631\u0627\u0647\u06cc\u0645\u060c \u0627\u06cc\u0646 \u0642\u062f\u0631 \u062c\u0627\u0645\u0639 \u0627\u0644\u0627\u0637\u0631\u0627\u0641 \u0628\u0627\u0634\u062f \u0631\u0627 \u0646\u062f\u06cc\u062f\u0645. \u0645\u062d\u0628\u062a \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0634\u0627\u0645\u0644 \u062d\u0627\u0644 \u0647\u0645\u0647 \u0645\u06cc \u0634\u062f. \u0627\u0632 \u0627\u0633\u0631\u0627\u06cc \u0639\u0631\u0627\u0642\u06cc \u062a\u0627 \u0628\u0631\u062e\u06cc \u0631\u0632\u0645\u0646\u062f\u06af\u0627\u0646 \u06a9\u0647 \u0627\u0632 \u0646\u0642\u0627\u0637 \u062f\u0648\u0631 \u062f\u0633\u062a \u0627\u06cc\u0631\u0627\u0646 \u0622\u0645\u062f\u0647 \u0628\u0648\u062f\u0646\u062f. \u0627\u06cc\u0646 \u0639\u0634\u0642 \u0648 \u0645\u062d\u0628\u062a\u060c \u0638\u0627\u0647\u0631\u06cc \u0647\u0645 \u0646\u0628\u0648\u062f. \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0628\u0627 \u0639\u0634\u0642 \u0648 \u0639\u0644\u0627\u0642\u0647 \u0628\u0647 \u062f\u06cc\u06af\u0631\u0627\u0646 \u062e\u062f\u0645\u062a \u0645\u06cc \u06a9\u0631\u062f. \u0627\u06cc\u0646\u06a9\u0647 \u0628\u0628\u06cc\u0646\u062f \u06cc\u06a9 \u0628\u0646\u062f\u0647 \u062e\u062f\u0627 \u0627\u0630\u06cc\u062a \u0645\u06cc \u0634\u0648\u062f\u060c \u0628\u0631\u0627\u06cc \u0627\u0648 \u0628\u0633\u06cc\u0627\u0631 \u0633\u062e\u062a \u0628\u0648\u062f.\n\u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u0648 \u0641\u0631\u0645\u0627\u0646\u062f\u0647\u06cc \u0642\u0628\u0648\u0644 \u0646\u0645\u06cc \u06a9\u0631\u062f. \u0634\u0627\u06cc\u062f \u06cc\u06a9\u06cc \u0627\u0632 \u062f\u0644\u0627\u06cc\u0644\u0634 \u0627\u06cc\u0646 \u0628\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a\u060c \u0627\u0645\u06a9\u0627\u0646 \u062f\u0627\u0631\u062f \u0627\u0646\u0633\u0627\u0646 \u062a\u0635\u0645\u06cc\u0645 \u062f\u0631\u0633\u062a\u06cc \u0646\u06af\u06cc\u0631\u062f \u0648 \u0647\u0645\u06cc\u0646 \u0628\u0627\u0639\u062b \u0631\u0646\u062c\u0634 \u0627\u0637\u0631\u0627\u0641\u06cc\u0627\u0646 \u0634\u0648\u062f. \u0628\u0631\u0627\u06cc \u0647\u0645\u06cc\u0646 \u0647\u0645\u06cc\u0634\u0647 \u0645\u06cc \u06af\u0641\u062a: \u06cc\u06a9 \u0646\u0641\u0631 \u0627\u0632 \u062f\u0648\u0633\u062a\u0627\u0646\u060c \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u0631\u0627 \u0642\u0628\u0648\u0644 \u06a9\u0646\u062f \u0648 \u0645\u0627 \u0628\u0627 \u062a\u0645\u0627\u0645 \u062a\u0648\u0627\u0646 \u062f\u0631 \u06a9\u0646\u0627\u0631\u0634 \u0647\u0633\u062a\u06cc\u0645. \u06a9\u0647 \u062f\u06cc\u06af\u0631 \u0627\u06cc\u0646\u06a9\u0647 \u0642\u0644\u0628 \u0631\u0626\u0648\u0641 \u0648 \u0645\u0647\u0631\u0628\u0627\u0646 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0628\u0647 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u0647\u0645 \u0645\u062d\u0628\u062a \u062f\u0627\u0634\u062a. \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u0633\u062a \u0628\u0628\u06cc\u0646\u062f \u06a9\u0647 \u06cc\u06a9 \u062d\u06cc\u0648\u0627\u0646 \u0627\u0630\u06cc\u062a \u0645\u06cc \u0634\u0648\u062f. \u0628\u062e\u0634 \u0631\u0648\u0632 \u0642\u0631\u0627\u0631 \u0634\u062f \u06a9\u0647 \u0628\u0627 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645\u060c \u0627\u0632 \u06af\u06cc\u0644\u0627\u0646 \u063a\u0631\u0628 \u0628\u0647 \u06a9\u0631\u0645\u0627\u0646\u0634\u0627\u0647 \u0648 \u0627\u0632 \u0622\u0646\u062c\u0627 \u0628\u0647 \u062a\u0647\u0631\u0627\u0646 \u062a\u06cc\u0645 \u0633\u0648\u0627\u0631 \u0645\u06cc\u0646\u06cc \u0628\u0648\u0633 \u0648 \u0631\u0627\u0647\u06cc \u06a9\u0631\u0645\u0627\u0646\u0634\u0627\u0647 \u0634\u062f\u06cc\u0645.\n\u062f\u0627\u0646\u0644\u0648\u062f \u0631\u0627\u06cc\u06af\u0627\u0646 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 1\n\u0645\u062f\u062a\u06cc \u067e\u0633 \u0627\u0632 \u0627\u0646\u062a\u0634\u0627\u0631 \u062c\u0644\u062f \u0627\u0648\u0644 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645\u060c \u0646\u0627\u0634\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u0631\u0627\u06cc\u06af\u0627\u0646 \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0645\u0646\u062a\u0634\u0631 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0648 \u062f\u0631 \u0622\u062f\u0631\u0633 \u0630\u06cc\u0644 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0634\u0645\u0627\u0633\u062a.\n\n\n\n\u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#%D9%BE%DB%8C_%D8%AF%DB%8C_%D8%A7%D9%81_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%AC%D9%84%D8%AF_%DB%B1_%D9%88_%DB%B2\" >\u067e\u06cc \u062f\u06cc \u0627\u0641 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u062c\u0644\u062f \u06f1 \u0648 \u06f2<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%B5%D9%88%D8%AA%DB%8C\" >\u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0635\u0648\u062a\u06cc<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%87%D8%A7%D8%AF%DB%8C\"><\/span>\u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0633\u062a\u0627\u062f \u067e\u0646\u0627\u0647\u064a\u0627\u0646 \u062f\u0631 \u064a\u0627\u062f\u0648\u0627\u0631\u0647 \u0634\u0647\u062f\u0627\u064a \u06a9\u0627\u0646\u0627\u0644 \u06a9\u0645\u064a\u0644 \u062f\u0631 \u0631\u0648\u0632 \u062c\u0648\u0627\u0646\u060c \u062e\u0631\u062f\u0627\u062f\u0645\u0627\u0647 \u06f1\u06f3\u06f9\u06f4 \u062f\u0631\u0628\u0627\u0631\u0647 \u0627\u06cc \u0634\u0647\u06cc\u062f \u0628\u0632\u0631\u06af\u0648\u0627\u0631 \u06af\u0641\u062a\u0646\u062f: \u0634\u0647\u064a\u062f \u0627\u0628\u0631\u0627\u0647\u064a\u0645 \u0647\u0627\u062f\u064a \u062f\u0631 \u0628\u064a\u0646 \u06f2\u06f5\u06f0 \u0647\u0632\u0627\u0631 \u0634\u0647\u064a\u062f\u064a \u06a9\u0647 \u062f\u0631 \u0637\u0648\u0644 \u062f\u0641\u0627\u0639 \u0645\u0642\u062f\u0633 \u062a\u0642\u062f\u064a\u0645 \u06a9\u0631\u062f\u0647\u200c\u0627\u064a\u0645\u060c \u064a\u06a9 \u0634\u0647\u064a\u062f \u0628\u0631\u062c\u0633\u062a\u0647 \u0627\u0633\u062a.<br \/>\n\u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u0642\u0627\u0645 \u0639\u0638\u0645\u0627\u06cc \u0648\u0644\u0627\u06cc\u062a \u062f\u0631 \u0645\u0648\u0631\u062f \u06a9\u062a\u0627\u0628 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc \u0641\u0631\u0645\u0648\u062f\u0646\u062f: \u00ab\u0627\u062e\u064a\u0631\u0627\u064b \u06a9\u062a\u0627\u0628\u064a \u062f\u0631\u0628\u0627\u0631\u0647 \u0634\u0647\u064a\u062f \u0627\u0628\u0631\u0627\u0647\u064a\u0645 \u0647\u0627\u062f\u064a (\u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u064a\u0645) \u0631\u0627 \u062e\u0648\u0627\u0646\u062f\u0647\u200c\u0627\u0645\u060c \u0628\u0627 \u0648\u062c\u0648\u062f \u0627\u064a\u0646\u06a9\u0647 \u0645\u0637\u0627\u0644\u0639\u0647 \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0627\u062a\u0645\u0627\u0645 \u0631\u0633\u0627\u0646\u062f\u0647\u200c\u0627\u0645\u060c \u0627\u0645\u0627 \u0647\u0646\u0648\u0632 \u06a9\u062a\u0627\u0628 \u0631\u0627 \u06a9\u0646\u0627\u0631 \u0646\u06af\u0630\u0627\u0634\u062a\u0647\u200c\u0627\u0645.\u00bb<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B2%D9%86%D8%AF%DA%AF%DB%8C%D9%86%D8%A7%D9%85%D9%87_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%87%D8%A7%D8%AF%DB%8C\"><\/span>\u0632\u0646\u062f\u06af\u06cc\u0646\u0627\u0645\u0647 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062e\u062f\u0627 \u062e\u0648\u0627\u0633\u062a\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0648 \u062f\u0631 \u06cc\u06a9 \u0645\u062d\u0644\u0647\u200c\u0627\u06cc \u062f\u0631 \u0648\u0633\u0637 \u062a\u0647\u0631\u0627\u0646 \u0632\u0646\u062f\u06af\u06cc \u06a9\u0646\u062f \u0648 \u06cc\u06a9\u06cc \u0627\u0632 \u062c\u0648\u0627\u0646\u200c\u0647\u0627\u06cc \u0634\u0647\u0631 \u0645\u0627 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u0627 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a \u0648 \u0627\u06cc\u0646 \u062a\u0641\u0627\u0648\u062a \u0628\u0647 \u0633\u0627\u062f\u06af\u06cc \u0645\u0644\u0645\u0648\u0633 \u0627\u0633\u062a. \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u0646\u0647 \u0639\u0627\u0644\u0645 \u062f\u06cc\u0646\u06cc \u0628\u0648\u062f\u060c \u0646\u0647 \u062c\u0632\u0621 \u0641\u0631\u0645\u0627\u0646\u062f\u0647\u0627\u0646 \u06cc\u0627 \u0633\u0631\u062f\u0627\u0631\u0627\u0646 \u062f\u0641\u0627\u0639 \u0645\u0642\u062f\u0633(\u0628\u0647 \u0645\u0639\u0646\u0627\u06cc \u062e\u0627\u0635 \u06a9\u0644\u0645\u0647) \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u062f\u060c \u0628\u0644\u06a9\u0647 \u0627\u0648 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u06cc\u0627\u0646 \u0645\u0631\u062f\u0645 \u0628\u0648\u062f. \u067e\u062f\u0631 \u0628\u0632\u0631\u06af\u0648\u0627\u0631 \u0627\u06cc\u0634\u0627\u0646 \u0647\u0645 \u06cc\u06a9 \u06a9\u0627\u0633\u0628 \u0645\u0639\u0645\u0648\u0644\u06cc \u0628\u0648\u062f \u0648 \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631 \u0628\u0642\u0627\u0644\u06cc \u062f\u0627\u0634\u062a\u0647. \u0634\u0627\u06cc\u062f \u06cc\u06a9\u06cc \u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0648 \u0631\u0627 \u0645\u0645\u062a\u0627\u0632 \u0645\u06cc\u200c\u06a9\u0631\u062f\u060c \u0627\u06cc\u0646 \u0628\u0648\u062f \u06a9\u0647 \u0627\u06cc\u0634\u0627\u0646 \u06cc\u06a9 \u0648\u0631\u0632\u0634\u06a9\u0627\u0631- \u0628\u0647 \u062a\u0645\u0627\u0645 \u0645\u0639\u0646\u0627\u06cc \u06a9\u0644\u0645\u0647- \u0628\u0648\u062f. \u0633\u0644\u0648\u06a9\u06cc \u06a9\u0647 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc \u062f\u0631 \u06af\u0648\u062f \u0632\u0648\u0631\u062e\u0627\u0646\u0647 \u062f\u0627\u0634\u062a\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0645\u0639\u0644\u0648\u0645 \u0627\u0633\u062a. \u06a9\u0647 \u0628\u0639\u062f \u0647\u0645 \u062f\u0631 \u062c\u0628\u0647\u0647\u200c\u0647\u0627 \u062d\u0627\u0636\u0631 \u0634\u062f. \u062d\u0645\u0627\u0633\u0629 \u06a9\u0627\u0646\u0627\u0644 \u06a9\u0645\u06cc\u0644 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0644\u062d\u0638\u0627\u062a \u0633\u0631\u0627\u0633\u0631 \u067e\u0631\u0646\u0648\u0631 \u062f\u0641\u0627\u0639 \u0645\u0642\u062f\u0633\u060c \u0648\u0627\u0642\u0639\u0627\u064b \u0628\u0631\u062c\u0633\u062a\u0647 \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u062f\u0631 \u0639\u06cc\u0646 \u062d\u0627\u0644\u060c \u06a9\u0627\u0646\u0627\u0644 \u06a9\u0645\u06cc\u0644 \u0628\u0647 \u0634\u0647\u06cc\u062f \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc \u0627\u0641\u062a\u062e\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0627\u06cc\u0646 \u0634\u0647\u06cc\u062f \u0628\u0631\u0627\u06cc \u06a9\u0627\u0646\u0627\u0644 \u06a9\u0645\u06cc\u0644 \u06cc\u06a9 \u0627\u0641\u062a\u062e\u0627\u0631 \u062c\u0627\u0648\u062f\u0627\u0646\u0647 \u0627\u0633\u062a.<br \/>\n\u0627\u0648 \u06cc\u06a9 \u0648\u0631\u0632\u0634\u06a9\u0627\u0631 \u062c\u0648\u0627\u0646\u0645\u0631\u062f \u0628\u0648\u062f. \u0648 \u06a9\u0633\u06cc \u06a9\u0647 \u0622\u0646 \u0647\u06cc\u06a9\u0644 \u0648\u0631\u0632\u0634\u06a9\u0627\u0631\u06cc \u0648 \u0622\u0646 \u0645\u0646\u0634 \u062c\u0648\u0627\u0646\u0645\u0631\u062f\u06cc \u0631\u0627 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0637\u0628\u06cc\u0639\u062a\u0627\u064b \u0645\u0648\u0631\u062f \u062a\u0648\u062c\u0647 \u062f\u06cc\u06af\u0631 \u062c\u0648\u0627\u0646\u0627\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u06cc\u06a9 \u0628\u0627\u0631 \u06a9\u0647 \u0628\u0627 \u0622\u0646 \u0647\u06cc\u06a9\u0644 \u0648\u0631\u0632\u0634\u06a9\u0627\u0631\u06cc \u0648 \u0633\u0627\u06a9 \u062f\u0633\u062a\u06cc \u0628\u0647 \u0633\u0645\u062a \u0632\u0648\u0631\u062e\u0627\u0646\u0647 \u0645\u06cc\u200c\u0631\u0641\u062a\u060c \u0631\u0641\u0642\u0627\u06cc\u0634 \u0628\u0647 \u0627\u0648 \u0645\u06cc\u200c\u06af\u0648\u06cc\u0646\u062f: \u00ab\u062f\u0648 \u062a\u0627 \u062f\u062e\u062a\u0631 \u0645\u062d\u0644\u060c \u062f\u0646\u0628\u0627\u0644 \u062a\u0648 \u0627\u0641\u062a\u0627\u062f\u0647 \u0628\u0648\u062f\u0646\u062f \u0648 \u062f\u0631\u0628\u0627\u0631\u0629 \u062a\u0648 \u062d\u0631\u0641 \u0645\u06cc\u200c\u0632\u062f\u0646\u062f. \u0645\u0627\u0634\u0627\u0621\u0627\u0644\u0644\u0647 \u062e\u0648\u0628 \u062f\u0644\u0628\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc!\u00bb \u0645\u06cc\u200c\u06af\u0648\u06cc\u0646\u062f \u0627\u0632 \u0641\u0631\u062f\u0627 \u062f\u06cc\u06af\u0631 \u0633\u0627\u06a9 \u0648\u0631\u0632\u0634\u06cc \u0628\u0631 \u0646\u0645\u06cc\u200c\u062f\u0627\u0631\u062f! \u0644\u0628\u0627\u0633\u200c\u0647\u0627\u06cc \u0648\u0631\u0632\u0634 \u062e\u0648\u062f\u0634 \u0631\u0627 \u062f\u0627\u062e\u0644 \u06cc\u06a9 \u0645\u0634\u0645\u0627 (\u06a9\u06cc\u0633\u0647) \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u062f\u060c \u0648 \u06cc\u06a9 \u067e\u06cc\u0631\u0627\u0647\u0646 \u06af\u0634\u0627\u062f \u0645\u06cc\u200c\u067e\u0648\u0634\u062f&#8230;<br \/>\n\u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0627\u0632 \u0627\u0648 \u0646\u0642\u0644 \u0634\u062f\u0647 \u06a9\u0647 \u0686\u0647 \u062c\u0648\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u0631\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0627\u062f\u0647 \u0648 \u0627\u0632 \u06a9\u062f\u0627\u0645 \u0646\u0642\u0637\u0647 \u0628\u0647 \u06a9\u062f\u0627\u0645 \u0646\u0642\u0637\u0647 \u0631\u0633\u0627\u0646\u062f\u0647 \u0627\u0633\u062a\u061b \u0627\u0632 \u0647\u0631\u0632\u06af\u06cc \u0628\u0647 \u062d\u0636\u0648\u0631 \u062f\u0631 \u062c\u0628\u0647\u0647\u200c\u0647\u0627\u06cc \u062c\u0646\u06af \u0631\u0633\u0627\u0646\u062f\u0647 \u0627\u0633\u062a. \u0627\u0648 \u062d\u062a\u06cc \u062a\u0648\u0627\u0646\u0633\u062a\u0647 \u0628\u0648\u062f \u0639\u0631\u0627\u0642\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0631\u0627 \u06a9\u0647 \u062f\u0631 \u062c\u0628\u0647\u0629 \u0645\u0642\u0627\u0628\u0644 \u0627\u0648 \u0628\u0648\u062f\u0646\u062f \u0648 \u062f\u0631 \u0633\u0646\u06af\u0631 \u062e\u0648\u062f\u0634\u0627\u0646 \u062f\u0631 \u062d\u0627\u0644 \u062a\u06cc\u0631\u0627\u0646\u062f\u0627\u0632\u06cc \u0628\u0648\u062f\u0646\u062f\u060c \u062c\u0630\u0628 \u06a9\u0646\u062f \u0648 \u062a\u0633\u0644\u06cc\u0645 \u06a9\u0646\u062f \u0648 \u0627\u06cc\u0646 \u0637\u0631\u0641 \u0628\u06cc\u0627\u0648\u0631\u062f. \u062f\u0631 \u06cc\u06a9 \u0633\u062d\u0631\u06af\u0627\u0647 &#8230;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%88%D8%B5%DB%8C%D8%AA_%D9%86%D8%A7%D9%85%D9%87_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%87%D8%A7%D8%AF%DB%8C\"><\/span>\u0648\u0635\u06cc\u062a \u0646\u0627\u0645\u0647 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0628\u0631\u0627\u0647\u064a\u0645 \u0648\u0635\u064a\u062a\u0646\u0627\u0645\u0647 \u064a \u0645\u0643\u062a\u0648\u0628 \u0646\u062f\u0627\u0631\u062f\u060c \u0627\u0645\u0627 \u062f\u0631 \u062d\u0643\u0627\u064a\u062a \u0647\u0627\u064a \u0646\u0642\u0644 \u0634\u062f\u0647 \u0627\u0632 \u0627\u0648\u060c \u062f\u0631\u0633 \u0647\u0627\u064a \u0639\u0645\u064a\u0642 \u062a\u0631\u0628\u064a\u062a\u064a \u0646\u0647\u0641\u062a\u0647 \u0627\u0633\u062a \u0643\u0647 \u0628\u0631\u0627\u064a \u0628\u064a\u062f\u0627\u0631\u064a \u0648\u062c\u062f\u0627\u0646 \u0647\u0627\u064a \u063a\u0641\u0644\u062a \u0632\u062f\u0647\u060c \u0628\u0633\u064a\u0627\u0631 \u0643\u0627\u0631\u0628\u0631\u062f \u062f\u0627\u0631\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%DB%B2\"><\/span>\u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u06f2<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0632 \u0628\u0686\u06af\u06cc \u0628\u0647 \u0645\u0627 \u06af\u0641\u062a\u0647 \u0627\u0646\u062f \u06a9\u0647 \u0634\u0647\u06cc\u062f \u0634\u062f\u0646 \u0644\u06cc\u0627\u0642\u062a \u0645\u06cc\u062e\u0648\u0627\u0647\u062f\u060c \u062f\u0631\u0633\u062a \u06af\u0641\u062a\u0647 \u0627\u0646\u062f\u060c \u0686\u0648\u0646 \u06a9\u0645\u062a\u0631 \u06a9\u0633\u0627\u0646\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062e\u062f\u0627\u0648\u0646\u062f \u0622\u0646\u0647\u0627 \u0631\u0627 \u0622\u0646\u0642\u062f\u0631 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u0647 \u0622\u0646\u0647\u0627 \u0633\u0639\u0627\u062f\u062a \u0634\u0647\u06cc\u062f \u0634\u062f\u0646 \u0631\u0627 \u0628\u062f\u0647\u062f. \u0627\u0648\u0644\u06cc\u0646 \u0634\u0631\u0637 \u0628\u0631\u0627\u06cc \u0634\u0647\u06cc\u062f \u0634\u062f\u0646\u060c \u0645\u0627\u0646\u0646\u062f \u0634\u0647\u062f\u0627 \u0632\u0646\u062f\u06af\u06cc \u06a9\u0631\u062f\u0646 \u0627\u0633\u062a\u061b \u0645\u062b\u0644\u0627 \u0628\u0628\u06cc\u0646\u06cc\u0645 \u0631\u0641\u062a\u0627\u0631 \u0648 \u0627\u0639\u0645\u0627\u0644 \u0634\u0647\u062f\u0627 \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0634\u062e\u0635\u06cc \u0634\u0627\u0646 \u0686\u06af\u0648\u0646\u0647 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a\u061f \u0622\u06cc\u0627 \u0622\u0646 \u0647\u0627 \u0647\u0645\u200c \u0645\u0627\u0646\u0646\u062f \u0627\u0641\u0631\u0627\u062f \u0645\u0639\u0645\u0648\u0644\u06cc \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u06af\u0646\u0627\u0647 \u0645\u06cc\u06a9\u0631\u062f\u0646\u062f\u061f \u0646\u0645\u0627\u0632 \u0634\u0628 \u0686\u0647 \u062a\u0627\u062b\u06cc\u0631\u06cc \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a\u061f \u0648 \u0647\u0632\u0627\u0631\u0627\u0646 \u0633\u0648\u0627\u0644 \u062f\u06cc\u06af\u0631 \u06a9\u0647 \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u0645 \u0627\u0632 \u062e\u0648\u062f \u0628\u067e\u0631\u0633\u06cc\u0645.<\/p>\n<p>\u0642\u0637\u0639\u0627 \u200c\u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0634\u0647\u06cc\u062f \u0634\u062f\u0647 \u0627\u0646\u062f \u0645\u062b\u0644 \u0622\u062f\u0645 \u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u06af\u0646\u0627\u0647 \u0646\u0645\u06cc \u06a9\u0631\u062f\u0646\u062f\u061b \u0622\u0646\u0627\u0646 \u0627\u0648\u0644 \u0646\u0641\u0633 \u0627\u0645\u0627\u0631\u0647 \u062e\u0648\u062f \u0631\u0627 \u06a9\u0634\u062a\u0647 \u0627\u0646\u062f \u0648 \u0628\u0647 \u0645\u0633\u0627\u0626\u0644 \u0644\u0630\u062a \u0628\u062e\u0634 \u0648 \u0634\u0647\u0648\u0627\u0646\u06cc \u0627\u06cc\u0646 \u062f\u0646\u06cc\u0627 \u067e\u0634\u062a \u06a9\u0631\u062f\u0647 \u0627\u0646\u062f\u060c \u0627\u06cc\u0646 \u0628\u0632\u0631\u06af \u0645\u0631\u062f\u0627\u0646 \u0627\u0632 \u0632\u0646 \u0648 \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u0648 \u062d\u062a\u06cc \u062c\u0627\u0646 \u0634\u06cc\u0631\u06cc\u0646 \u0634\u0627\u0646 \u06af\u0630\u0634\u062a\u0646\u062f \u062a\u0627 \u0628\u0647 \u0648\u0627\u062c\u0628 \u062e\u062f\u0627\u0648\u0646\u062f \u0639\u0645\u0644 \u06a9\u0646\u0646\u062f. \u0622\u0646\u0647\u0627 \u0628\u0631\u0627\u06cc \u0622\u0631\u0627\u0645\u0634 \u0645\u0631\u062f\u0645 \u06a9\u0634\u0648\u0631\u0634\u0627\u0646 \u062c\u0627\u0646 \u062e\u0648\u062f \u0631\u0627 \u0641\u062f\u0627 \u06a9\u0631\u062f\u0646\u062f \u062a\u0627 \u0645\u0627 \u062f\u0631 \u0622\u0631\u0627\u0645\u0634 \u0628\u062e\u0648\u0627\u0628\u06cc\u0645. \u062d\u062a\u0645\u0627 \u0686\u0646\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f\u06cc \u0628\u0631\u0646\u0627\u0645\u0647 \u062e\u0627\u0635\u06cc \u0628\u0631\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0627\u0646\u062f. \u0628\u0631\u0627\u06cc \u0622\u0634\u0646\u0627 \u0634\u062f\u0646 \u0628\u0627 \u0634\u06cc\u0648\u0647 \u0632\u0646\u062f\u06af\u06cc \u0645\u0631\u062f\u0627\u0646 \u062e\u062f\u0627 \u06a9\u062a\u0627\u0628 \u0647\u0627\u06cc\u06cc \u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u06a9\u0647 \u0631\u0648\u0627\u06cc\u062a \u06af\u0631 \u062f\u0627\u0633\u062a\u0627\u0646 \u0632\u0646\u062f\u06af\u06cc \u0622\u0646\u0627\u0646 \u0627\u0633\u062a.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AE%D9%84%D8%A7%D8%B5%D9%87_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_2\"><\/span>\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2\u060c \u062f\u0627\u0633\u062a\u0627\u0646 \u0632\u0646\u062f\u06af\u06cc \u0634\u0647\u06cc\u062f \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc \u0631\u0627 \u0631\u0648\u0627\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f\u061b \u0634\u0647\u06cc\u062f\u06cc \u06a9\u0647 \u0647\u0646\u0648\u0632 \u067e\u06cc\u06a9\u0631\u0634 \u062f\u0631 \u06a9\u0631\u0628\u0644\u0627\u06cc \u0641\u06a9\u0647 \u06af\u0645\u0646\u0627\u0645 \u0628\u0627\u0642\u06cc \u0645\u0627\u0646\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0634\u0647\u06cc\u062f \u06af\u0631\u0627\u0646\u0642\u062f\u0631 \u0627\u0644\u06af\u0648\u06cc \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0631\u0627\u06cc \u062c\u0648\u0627\u0646\u0627\u0646 \u0645\u06cc\u0628\u0627\u0634\u062f\u060c \u0686\u0631\u0627 \u06a9\u0647 \u062f\u0631 \u0639\u06cc\u0646 \u0634\u0648\u0631 \u0648 \u0634\u0648\u0642 \u062c\u0648\u0627\u0646\u06cc\u060c \u0628\u0633\u06cc\u0627\u0631 \u0645\u062a\u06cc\u0646 \u0648 \u0628\u0627\u062e\u062f\u0627 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u06af\u0631\u0648\u0647 \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646 \u0627\u0646\u062c\u0645\u0646 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0631\u0627 \u0628\u0631 \u0637\u0628\u0642 \u062e\u0627\u0637\u0631\u0627\u062a \u0627\u06cc\u0634\u0627\u0646 \u0628\u0627 \u062f\u0648\u0633\u062a\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0628\u0647 \u0631\u0634\u062a\u0647 \u062a\u062d\u0631\u06cc\u0631 \u062f\u0631 \u0622\u0648\u0631\u062f\u0647 \u0627\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0631\u0648\u0627\u0628\u0637 \u0627\u06cc\u0646 \u0634\u0647\u06cc\u062f \u0639\u0632\u06cc\u0632 \u0631\u0627 \u0628\u0627 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u060c \u062f\u0648\u0633\u062a\u0627\u0646 \u0648 \u062d\u062a\u06cc \u062d\u062c\u0628 \u0648 \u062d\u06cc\u0627\u06cc \u0627\u06cc\u0634\u0627\u0646 \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0646\u0627 \u0645\u062d\u0631\u0645 \u0631\u0627 \u062a\u0648\u0636\u06cc\u062d \u0645\u06cc\u062f\u0647\u062f. \u0686\u0631\u0627 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u062f\u0648\u061f \u062f\u0631 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u06cc\u06a9 \u0628\u0639\u0636\u06cc\u200c \u0627\u0632 \u062e\u0627\u0637\u0631\u0627\u062a \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0646\u0628\u0648\u062f\u0646 \u0631\u0627\u0648\u06cc\u0627\u0646 \u0686\u0627\u067e \u0646\u0634\u062f\u060c \u0628\u0631\u0627\u06cc \u0647\u0645\u06cc\u0646 \u062a\u0645\u0627\u0645 \u062e\u0627\u0637\u0631\u0627\u062a \u0628\u0627\u0642\u06cc \u0645\u0627\u0646\u062f\u0647 \u0631\u0627 \u062f\u0631 \u062c\u0644\u062f \u062f\u0648\u0645 \u0622\u0646 \u06a9\u062a\u0627\u0628 \u0686\u0627\u067e \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f.<\/p>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0647\u0645 \u0645\u0627\u0646\u0646\u062f \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 1\u060c \u062e\u0627\u0637\u0631\u0627\u062a\u06cc \u06a9\u0648\u062a\u0627\u0647 \u0648 \u062f\u0648 \u0633\u0647 \u0635\u0641\u062d\u0647\u200c\u0627\u06cc \u0627\u0632 \u0631\u0627\u0648\u06cc\u0627\u0646 \u0645\u062e\u062a\u0644\u0641 \u0627\u0631\u0627\u0626\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a.<br \/>\n<div class=\"special-product\">\n\t                            <div class=\"special-product__content\">\n\t                                <a class=\"special-product__thumbnail\" href=\"https:\/\/faraketab.ir\/book\/16005\" title=\"\u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 (\u062c\u0644\u062f \u062f\u0648\u0645)\">\t                                   \n\t                                    \n\t                                    <picture >\n\t                                        <source type = \"image\/avif\" srcset = \"https:\/\/file1.cdn.faraketab.ir\/content_file\/content-1-16005-105526\/%D8%B3%D9%84%D8%A7%D9%85%20%D8%A8%D8%B1%20%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85%20%28%D8%AC%D9%84%D8%AF%20%D8%AF%D9%88%D9%85%29.jpg\" >\n\t                                        <source type = \"image\/webp\" srcset = \"https:\/\/file1.cdn.faraketab.ir\/content_file\/content-1-16005-105526\/%D8%B3%D9%84%D8%A7%D9%85%20%D8%A8%D8%B1%20%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85%20%28%D8%AC%D9%84%D8%AF%20%D8%AF%D9%88%D9%85%29.jpg\" >\n\t                                        <img class=\"product-thumbnail\" srcset = \"https:\/\/file1.cdn.faraketab.ir\/content_file\/content-1-16005-105526\/%D8%B3%D9%84%D8%A7%D9%85%20%D8%A8%D8%B1%20%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85%20%28%D8%AC%D9%84%D8%AF%20%D8%AF%D9%88%D9%85%29.jpg\" alt = \"\" title = \"\" >\n\t                                    <\/picture >\n\t                                    <div class=\"detail\" >\n\t                                        <div class=\"rate\"><i class='fa fa-star active'><\/i><i class='fa fa-star active'><\/i><i class='fa fa-star active'><\/i><i class='fa fa-star active'><\/i><i class='fa fa-star active'><\/i><\/div >\n\t                                        <div class=\"type\" >\n\t                                           <i class='far fa-file active'><\/i>\n                    <i class='far fa-headphones '><\/i>\n                    <i class='far fa-book '><\/i>\n\t                                        <\/div >\n\t                                    <\/div >\n\t                                <\/a>\n\t                                <div class=\"special-product__details\" >\n\t                                    <div>\n\t                                        <h3 class=\"title\" ><span class=\"ez-toc-section\" id=\"%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%AC%D9%84%D8%AF_%D8%AF%D9%88%D9%85_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_2_%DA%A9%D8%A7%D8%B1%DB%8C_%D8%A7%D8%B2_%DA%AF%D8%B1%D9%88%D9%87_%D9%86%D9%88%DB%8C%D8%B3%D9%86%D8%AF%DA%AF%D8%A7%D9%86_%D8%A7%D9%86%D8%AC%D9%85%D9%86_%D8%B4%D9%87%DB%8C%D8%AF_%D9%87%D8%A7%D8%AF%DB%8C_%D9%85%DB%8C_%D8%A8%D8%A7%D8%B4%D8%AF_%D9%88_%D8%A7%D9%86%D8%AA%D8%B4%D8%A7%D8%B1%D8%A7%D8%AA_%D8%B4%D9%87%DB%8C%D8%AF_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%87%D8%A7%D8%AF%DB%8C_%D8%A2%D9%86_%D8%B1%D8%A7_%D8%A8%D9%87_%DA%86%D8%A7%D9%BE_%D8%B1%D8%B3%D8%A7%D9%86%D8%AF%D9%87_%D8%A7%D8%B3%D8%AA_%D8%AE%D8%A7%D8%B7%D8%B1%D8%A7%D8%AA_%D8%A7%DB%8C%D9%86_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D8%B1_%D8%A7%D8%AF%D8%A7%D9%85%D9%87_%DA%A9_%DA%AF%D8%B1%D9%88%D9%87_%D9%86%D9%88%DB%8C%D8%B3%D9%86%D8%AF%DA%AF%D8%A7%D9%86_%D9%86%D9%88%DB%8C%D8%B3%D9%86%D8%AF%D9%87_%D8%A7%D9%86%D8%AA%D8%B4%D8%A7%D8%B1%D8%A7%D8%AA_%D8%B4%D9%87%DB%8C%D8%AF_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%87%D8%A7%D8%AF%DB%8C_%D9%86%D8%A7%D8%B4%D8%B1_%D9%BE%DB%8C%D8%B4_%D9%86%D9%85%D8%A7%DB%8C%D8%B4_%D9%88_%D8%AE%D8%B1%DB%8C%D8%AF_%D9%BE%DB%8C%D8%B4_%D9%86%D9%85%D8%A7%DB%8C%D8%B4_%D9%88_%D8%AE%D8%B1%DB%8C%D8%AF_%D8%A8%D8%B1%D8%B4%DB%8C_%D8%A7%D8%B2_%D9%85%D8%AA%D9%86_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%DB%B2_%D9%85%D9%86_%D8%A8%D8%A7_%D8%B4%D9%87%D8%AF%D8%A7%DB%8C_%D8%B2%DB%8C%D8%A7%D8%AF%DB%8C_%D8%AD%D8%B4%D8%B1_%D9%88_%D9%86%D8%B4%D8%B1_%D8%AF%D8%A7%D8%B4%D8%AA%D9%85_%D8%A7%D9%85%D8%A7_%D8%B4%D8%A8%DB%8C%D9%87_%D8%B4%D8%AE%D8%B5%DB%8C%D8%AA_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%B1%D8%A7_%D8%AF%D8%B1_%DA%A9%D9%85%D8%AA%D8%B1_%DA%A9%D8%B3%DB%8C_%D8%AF%DB%8C%D8%AF%D9%85_%D8%A8%D8%B1%D8%AE%DB%8C_%D8%A7%D9%81%D8%B1%D8%A7%D8%AF_%D8%A8%D9%88%D8%AF%D9%86%D8%AF_%DA%A9%D9%87_%D8%A8%D8%B9%D8%B6%DB%8C_%D8%A7%D8%B2_%D8%AE%D8%B5%D9%88%D8%B5%DB%8C%D8%A7%D8%AA_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%B1%D8%A7_%D8%AF%D8%A7%D8%B4%D8%AA%D9%86%D8%AF%D8%8C_%D8%A7%D9%85%D8%A7_%D8%A7%DB%8C%D9%86%DA%A9%D9%87_%DA%A9%D8%B3%DB%8C_%D9%85%D8%A7%D9%86%D9%86%D8%AF_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85%D8%8C_%D8%A7%DB%8C%D9%86_%D9%82%D8%AF%D8%B1_%D8%AC%D8%A7%D9%85%D8%B9_%D8%A7%D9%84%D8%A7%D8%B7%D8%B1%D8%A7%D9%81_%D8%A8%D8%A7%D8%B4%D8%AF_%D8%B1%D8%A7_%D9%86%D8%AF%DB%8C%D8%AF%D9%85_%D9%85%D8%AD%D8%A8%D8%AA_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%B4%D8%A7%D9%85%D9%84_%D8%AD%D8%A7%D9%84_%D9%87%D9%85%D9%87_%D9%85%DB%8C_%D8%B4%D8%AF_%D8%A7%D8%B2_%D8%A7%D8%B3%D8%B1%D8%A7%DB%8C_%D8%B9%D8%B1%D8%A7%D9%82%DB%8C_%D8%AA%D8%A7_%D8%A8%D8%B1%D8%AE%DB%8C_%D8%B1%D8%B2%D9%85%D9%86%D8%AF%DA%AF%D8%A7%D9%86_%DA%A9%D9%87_%D8%A7%D8%B2_%D9%86%D9%82%D8%A7%D8%B7_%D8%AF%D9%88%D8%B1_%D8%AF%D8%B3%D8%AA_%D8%A7%DB%8C%D8%B1%D8%A7%D9%86_%D8%A2%D9%85%D8%AF%D9%87_%D8%A8%D9%88%D8%AF%D9%86%D8%AF_%D8%A7%DB%8C%D9%86_%D8%B9%D8%B4%D9%82_%D9%88_%D9%85%D8%AD%D8%A8%D8%AA%D8%8C_%D8%B8%D8%A7%D9%87%D8%B1%DB%8C_%D9%87%D9%85_%D9%86%D8%A8%D9%88%D8%AF_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%A8%D8%A7_%D8%B9%D8%B4%D9%82_%D9%88_%D8%B9%D9%84%D8%A7%D9%82%D9%87_%D8%A8%D9%87_%D8%AF%DB%8C%DA%AF%D8%B1%D8%A7%D9%86_%D8%AE%D8%AF%D9%85%D8%AA_%D9%85%DB%8C_%DA%A9%D8%B1%D8%AF_%D8%A7%DB%8C%D9%86%DA%A9%D9%87_%D8%A8%D8%A8%DB%8C%D9%86%D8%AF_%DB%8C%DA%A9_%D8%A8%D9%86%D8%AF%D9%87_%D8%AE%D8%AF%D8%A7_%D8%A7%D8%B0%DB%8C%D8%AA_%D9%85%DB%8C_%D8%B4%D9%88%D8%AF%D8%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D9%88_%D8%A8%D8%B3%DB%8C%D8%A7%D8%B1_%D8%B3%D8%AE%D8%AA_%D8%A8%D9%88%D8%AF_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D9%85%D8%B3%D8%A6%D9%88%D9%84%DB%8C%D8%AA_%D9%88_%D9%81%D8%B1%D9%85%D8%A7%D9%86%D8%AF%D9%87%DB%8C_%D9%82%D8%A8%D9%88%D9%84_%D9%86%D9%85%DB%8C_%DA%A9%D8%B1%D8%AF_%D8%B4%D8%A7%DB%8C%D8%AF_%DB%8C%DA%A9%DB%8C_%D8%A7%D8%B2_%D8%AF%D9%84%D8%A7%DB%8C%D9%84%D8%B4_%D8%A7%DB%8C%D9%86_%D8%A8%D9%88%D8%AF_%DA%A9%D9%87_%D8%AF%D8%B1_%D8%B2%D9%85%D8%A7%D9%86_%D9%85%D8%B3%D8%A6%D9%88%D9%84%DB%8C%D8%AA%D8%8C_%D8%A7%D9%85%DA%A9%D8%A7%D9%86_%D8%AF%D8%A7%D8%B1%D8%AF_%D8%A7%D9%86%D8%B3%D8%A7%D9%86_%D8%AA%D8%B5%D9%85%DB%8C%D9%85_%D8%AF%D8%B1%D8%B3%D8%AA%DB%8C_%D9%86%DA%AF%DB%8C%D8%B1%D8%AF_%D9%88_%D9%87%D9%85%DB%8C%D9%86_%D8%A8%D8%A7%D8%B9%D8%AB_%D8%B1%D9%86%D8%AC%D8%B4_%D8%A7%D8%B7%D8%B1%D8%A7%D9%81%DB%8C%D8%A7%D9%86_%D8%B4%D9%88%D8%AF_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%87%D9%85%DB%8C%D9%86_%D9%87%D9%85%DB%8C%D8%B4%D9%87_%D9%85%DB%8C_%DA%AF%D9%81%D8%AA_%DB%8C%DA%A9_%D9%86%D9%81%D8%B1_%D8%A7%D8%B2_%D8%AF%D9%88%D8%B3%D8%AA%D8%A7%D9%86%D8%8C_%D9%85%D8%B3%D8%A6%D9%88%D9%84%DB%8C%D8%AA_%D8%B1%D8%A7_%D9%82%D8%A8%D9%88%D9%84_%DA%A9%D9%86%D8%AF_%D9%88_%D9%85%D8%A7_%D8%A8%D8%A7_%D8%AA%D9%85%D8%A7%D9%85_%D8%AA%D9%88%D8%A7%D9%86_%D8%AF%D8%B1_%DA%A9%D9%86%D8%A7%D8%B1%D8%B4_%D9%87%D8%B3%D8%AA%DB%8C%D9%85_%DA%A9%D9%87_%D8%AF%DB%8C%DA%AF%D8%B1_%D8%A7%DB%8C%D9%86%DA%A9%D9%87_%D9%82%D9%84%D8%A8_%D8%B1%D8%A6%D9%88%D9%81_%D9%88_%D9%85%D9%87%D8%B1%D8%A8%D8%A7%D9%86_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%A8%D9%87_%D8%AD%DB%8C%D9%88%D8%A7%D9%86%D8%A7%D8%AA_%D9%87%D9%85_%D9%85%D8%AD%D8%A8%D8%AA_%D8%AF%D8%A7%D8%B4%D8%AA_%DA%A9%D9%87_%D9%85%DB%8C_%D8%AA%D9%88%D8%A7%D9%86%D8%B3%D8%AA_%D8%A8%D8%A8%DB%8C%D9%86%D8%AF_%DA%A9%D9%87_%DB%8C%DA%A9_%D8%AD%DB%8C%D9%88%D8%A7%D9%86_%D8%A7%D8%B0%DB%8C%D8%AA_%D9%85%DB%8C_%D8%B4%D9%88%D8%AF_%D8%A8%D8%AE%D8%B4_%D8%B1%D9%88%D8%B2_%D9%82%D8%B1%D8%A7%D8%B1_%D8%B4%D8%AF_%DA%A9%D9%87_%D8%A8%D8%A7_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85%D8%8C_%D8%A7%D8%B2_%DA%AF%DB%8C%D9%84%D8%A7%D9%86_%D8%BA%D8%B1%D8%A8_%D8%A8%D9%87_%DA%A9%D8%B1%D9%85%D8%A7%D9%86%D8%B4%D8%A7%D9%87_%D9%88_%D8%A7%D8%B2_%D8%A2%D9%86%D8%AC%D8%A7_%D8%A8%D9%87_%D8%AA%D9%87%D8%B1%D8%A7%D9%86_%D8%AA%DB%8C%D9%85_%D8%B3%D9%88%D8%A7%D8%B1_%D9%85%DB%8C%D9%86%DB%8C_%D8%A8%D9%88%D8%B3_%D9%88_%D8%B1%D8%A7%D9%87%DB%8C_%DA%A9%D8%B1%D9%85%D8%A7%D9%86%D8%B4%D8%A7%D9%87_%D8%B4%D8%AF%DB%8C%D9%85_%D8%AF%D8%A7%D9%86%D9%84%D9%88%D8%AF_%D8%B1%D8%A7%DB%8C%DA%AF%D8%A7%D9%86_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_1_%D9%85%D8%AF%D8%AA%DB%8C_%D9%BE%D8%B3_%D8%A7%D8%B2_%D8%A7%D9%86%D8%AA%D8%B4%D8%A7%D8%B1_%D8%AC%D9%84%D8%AF_%D8%A7%D9%88%D9%84_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85%D8%8C_%D9%86%D8%A7%D8%B4%D8%B1_%D8%A7%DB%8C%D9%86_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%A2%D9%86_%D8%B1%D8%A7_%D8%A8%D9%87_%D8%B5%D9%88%D8%B1%D8%AA_%D8%B1%D8%A7%DB%8C%DA%AF%D8%A7%D9%86_%D8%AF%D8%B1_%D9%81%D8%B1%D8%A7%DA%A9%D8%AA%D8%A7%D8%A8_%D9%85%D9%86%D8%AA%D8%B4%D8%B1_%DA%A9%D8%B1%D8%AF%D9%87_%D8%A7%D8%B3%D8%AA_%D9%88_%D8%AF%D8%B1_%D8%A2%D8%AF%D8%B1%D8%B3_%D8%B0%DB%8C%D9%84_%D8%AF%D8%B1_%D8%AF%D8%B3%D8%AA%D8%B1%D8%B3_%D8%B4%D9%85%D8%A7%D8%B3%D8%AA_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85\"><\/span>\n\t                                            <a href=\"https:\/\/faraketab.ir\/book\/16005\" > \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 (\u062c\u0644\u062f \u062f\u0648\u0645)<\/a >        \n\t                                        <\/h3 >\n\t                                        <div class=\"description\" > \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2 \u06a9\u0627\u0631\u06cc \u0627\u0632 \u06af\u0631\u0648\u0647 \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646 \u0627\u0646\u062c\u0645\u0646 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f \u0648 \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0634\u0647\u06cc\u062f \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0686\u0627\u067e \u0631\u0633\u0627\u0646\u062f\u0647 \u0627\u0633\u062a. \u062e\u0627\u0637\u0631\u0627\u062a \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u06a9...<\/div >\n\t                                    <\/div>\n\t                                    <div class=\"caption\" ><div class=\"user\">\n            <img decoding=\"async\" loading=\"lazy\"\n                 src=\"https:\/\/www.faraketab.ir\/blog\/wp-content\/themes\/alizadeh\/images\/cover.png\"\n                 class=\"user__avatar\" alt=\"\"\/>\n            <div class=\"user__info\">\n                <div class=\"user__name\">\u06af\u0631\u0648\u0647 \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646<\/div>\n                <div class=\"user__job\">\u0646\u0648\u06cc\u0633\u0646\u062f\u0647<\/div>\n            <\/div>\n        <\/div><div class=\"user\">\n            <img decoding=\"async\" loading=\"lazy\"\n                 src=\"https:\/\/www.faraketab.ir\/blog\/wp-content\/themes\/alizadeh\/images\/cover.png\"\n                 class=\"user__avatar\" alt=\"\"\/>\n            <div class=\"user__info\">\n                <div class=\"user__name\">\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0634\u0647\u06cc\u062f \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc<\/div>\n                <div class=\"user__job\">\u0646\u0627\u0634\u0631<\/div>\n            <\/div>\n        <\/div><\/div >\n\t                                    <a href=\"https:\/\/faraketab.ir\/book\/16005\" class=\"btn\">\u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0634 \u0648 \u062e\u0631\u06cc\u062f<\/a>\n\t                                <\/div>\n\t                                 <a href=\"https:\/\/faraketab.ir\/book\/16005\" class=\"btn\">\u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0634 \u0648 \u062e\u0631\u06cc\u062f<\/a>\n\t                            <\/div>\n\t                        <\/div><\/p>\n<h2>\u0628\u0631\u0634\u06cc \u0627\u0632 \u0645\u062a\u0646 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u06f2<\/h2>\n<p>\u0645\u0646 \u0628\u0627 \u0634\u0647\u062f\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u062d\u0634\u0631 \u0648 \u0646\u0634\u0631 \u062f\u0627\u0634\u062a\u0645. \u0627\u0645\u0627 \u0634\u0628\u06cc\u0647 \u0634\u062e\u0635\u06cc\u062a \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0631\u0627 \u062f\u0631 \u06a9\u0645\u062a\u0631 \u06a9\u0633\u06cc \u062f\u06cc\u062f\u0645. \u0628\u0631\u062e\u06cc \u0627\u0641\u0631\u0627\u062f \u0628\u0648\u062f\u0646\u062f \u06a9\u0647 \u0628\u0639\u0636\u06cc \u0627\u0632 \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0631\u0627 \u062f\u0627\u0634\u062a\u0646\u062f\u060c \u0627\u0645\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u06a9\u0633\u06cc \u0645\u0627\u0646\u0646\u062f \u0627\u0628\u0631\u0627\u0647\u06cc\u0645\u060c \u0627\u06cc\u0646 \u0642\u062f\u0631 \u062c\u0627\u0645\u0639 \u0627\u0644\u0627\u0637\u0631\u0627\u0641 \u0628\u0627\u0634\u062f \u0631\u0627 \u0646\u062f\u06cc\u062f\u0645. \u0645\u062d\u0628\u062a \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0634\u0627\u0645\u0644 \u062d\u0627\u0644 \u0647\u0645\u0647 \u0645\u06cc \u0634\u062f. \u0627\u0632 \u0627\u0633\u0631\u0627\u06cc \u0639\u0631\u0627\u0642\u06cc \u062a\u0627 \u0628\u0631\u062e\u06cc \u0631\u0632\u0645\u0646\u062f\u06af\u0627\u0646 \u06a9\u0647 \u0627\u0632 \u0646\u0642\u0627\u0637 \u062f\u0648\u0631 \u062f\u0633\u062a \u0627\u06cc\u0631\u0627\u0646 \u0622\u0645\u062f\u0647 \u0628\u0648\u062f\u0646\u062f. \u0627\u06cc\u0646 \u0639\u0634\u0642 \u0648 \u0645\u062d\u0628\u062a\u060c \u0638\u0627\u0647\u0631\u06cc \u0647\u0645 \u0646\u0628\u0648\u062f. \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0628\u0627 \u0639\u0634\u0642 \u0648 \u0639\u0644\u0627\u0642\u0647 \u0628\u0647 \u062f\u06cc\u06af\u0631\u0627\u0646 \u062e\u062f\u0645\u062a \u0645\u06cc \u06a9\u0631\u062f. \u0627\u06cc\u0646\u06a9\u0647 \u0628\u0628\u06cc\u0646\u062f \u06cc\u06a9 \u0628\u0646\u062f\u0647 \u062e\u062f\u0627 \u0627\u0630\u06cc\u062a \u0645\u06cc \u0634\u0648\u062f\u060c \u0628\u0631\u0627\u06cc \u0627\u0648 \u0628\u0633\u06cc\u0627\u0631 \u0633\u062e\u062a \u0628\u0648\u062f.<\/p>\n<p>\u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u0648 \u0641\u0631\u0645\u0627\u0646\u062f\u0647\u06cc \u0642\u0628\u0648\u0644 \u0646\u0645\u06cc \u06a9\u0631\u062f. \u0634\u0627\u06cc\u062f \u06cc\u06a9\u06cc \u0627\u0632 \u062f\u0644\u0627\u06cc\u0644\u0634 \u0627\u06cc\u0646 \u0628\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a\u060c \u0627\u0645\u06a9\u0627\u0646 \u062f\u0627\u0631\u062f \u0627\u0646\u0633\u0627\u0646 \u062a\u0635\u0645\u06cc\u0645 \u062f\u0631\u0633\u062a\u06cc \u0646\u06af\u06cc\u0631\u062f \u0648 \u0647\u0645\u06cc\u0646 \u0628\u0627\u0639\u062b \u0631\u0646\u062c\u0634 \u0627\u0637\u0631\u0627\u0641\u06cc\u0627\u0646 \u0634\u0648\u062f. \u0628\u0631\u0627\u06cc \u0647\u0645\u06cc\u0646 \u0647\u0645\u06cc\u0634\u0647 \u0645\u06cc \u06af\u0641\u062a: \u06cc\u06a9 \u0646\u0641\u0631 \u0627\u0632 \u062f\u0648\u0633\u062a\u0627\u0646\u060c \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u0631\u0627 \u0642\u0628\u0648\u0644 \u06a9\u0646\u062f \u0648 \u0645\u0627 \u0628\u0627 \u062a\u0645\u0627\u0645 \u062a\u0648\u0627\u0646 \u062f\u0631 \u06a9\u0646\u0627\u0631\u0634 \u0647\u0633\u062a\u06cc\u0645. \u06a9\u0647 \u062f\u06cc\u06af\u0631 \u0627\u06cc\u0646\u06a9\u0647 \u0642\u0644\u0628 \u0631\u0626\u0648\u0641 \u0648 \u0645\u0647\u0631\u0628\u0627\u0646 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0628\u0647 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u0647\u0645 \u0645\u062d\u0628\u062a \u062f\u0627\u0634\u062a. \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u0633\u062a \u0628\u0628\u06cc\u0646\u062f \u06a9\u0647 \u06cc\u06a9 \u062d\u06cc\u0648\u0627\u0646 \u0627\u0630\u06cc\u062a \u0645\u06cc \u0634\u0648\u062f. \u0628\u062e\u0634 \u0631\u0648\u0632 \u0642\u0631\u0627\u0631 \u0634\u062f \u06a9\u0647 \u0628\u0627 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645\u060c \u0627\u0632 \u06af\u06cc\u0644\u0627\u0646 \u063a\u0631\u0628 \u0628\u0647 \u06a9\u0631\u0645\u0627\u0646\u0634\u0627\u0647 \u0648 \u0627\u0632 \u0622\u0646\u062c\u0627 \u0628\u0647 \u062a\u0647\u0631\u0627\u0646 \u062a\u06cc\u0645 \u0633\u0648\u0627\u0631 \u0645\u06cc\u0646\u06cc \u0628\u0648\u0633 \u0648 \u0631\u0627\u0647\u06cc \u06a9\u0631\u0645\u0627\u0646\u0634\u0627\u0647 \u0634\u062f\u06cc\u0645.<\/p>\n<h2>\u062f\u0627\u0646\u0644\u0648\u062f \u0631\u0627\u06cc\u06af\u0627\u0646 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 1<\/h2>\n<p>\u0645\u062f\u062a\u06cc \u067e\u0633 \u0627\u0632 \u0627\u0646\u062a\u0634\u0627\u0631 \u062c\u0644\u062f \u0627\u0648\u0644 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645\u060c \u0646\u0627\u0634\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u0631\u0627\u06cc\u06af\u0627\u0646 \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0645\u0646\u062a\u0634\u0631 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0648 \u062f\u0631 \u0622\u062f\u0631\u0633 \u0630\u06cc\u0644 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0634\u0645\u0627\u0633\u062a.<\/p>\n<div class=\"book\">\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/file1.cdn.faraketab.ir\/content_file\/content-1-10245-69051\/%D8%B3%D9%84%D8%A7%D9%85%20%D8%A8%D8%B1%20%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85%20%28%D8%AC%D9%84%D8%AF%20%D8%A7%D9%88%D9%84%29.avif\" alt=\"\u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 1\" width=\"400\" height=\"580\" \/><\/p>\n<div class=\"book__content\">\n<h3 class=\"book__title\">\u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p class=\"book__description\">\u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0646\u0647 \u062a\u0646\u0647\u0627 \u06cc\u0627\u062f\u0622\u0648\u0631 \u0634\u0647\u06cc\u062f\u06cc \u0642\u0647\u0631\u0645\u0627\u0646\u060c \u0628\u0644\u06a9\u0647 \u0628\u06cc\u0627\u0646\u06af\u0631 \u0627\u062d\u0648\u0627\u0644 \u0645\u0631\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u062f\u0627\u0634\u062a\u0646 \u0642\u0647\u0631\u0645\u0627\u0646\u06cc \u0647\u0627\u060c \u067e\u0647\u0644\u0648\u0627\u0646\u06cc \u0647\u0627\u060c \u0631\u0634\u0627\u062f\u062a \u0647\u0627\u060c \u0645\u0631\u0648\u062a \u0647\u0627 \u0648&#8230; \u0628\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u062f\u0627\u0644 \u0634\u0647\u0627\u062f\u062a \u06a9\u0645\u0627\u0644 \u06cc\u0627\u0641\u062a.<\/p>\n<p><a class=\"book__btn\" href=\"https:\/\/www.faraketab.ir\/book\/10245-%DA%A9%D8%AA%D8%A7%D8%A8-%D8%B3%D9%84%D8%A7%D9%85-%D8%A8%D8%B1-%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85\" target=\"_blank\" rel=\"noopener\"> \u062f\u0627\u0646\u0644\u0648\u062f \u0631\u0627\u06cc\u06af\u0627\u0646 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645<\/a><\/p>\n<\/div>\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D9%BE%DB%8C_%D8%AF%DB%8C_%D8%A7%D9%81_%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%AC%D9%84%D8%AF_%DB%B1_%D9%88_%DB%B2\"><\/span>\u067e\u06cc \u062f\u06cc \u0627\u0641 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u062c\u0644\u062f \u06f1 \u0648 \u06f2<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u06a9\u062a\u0627\u0628 \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644 \u062c\u0644\u062f \u0627\u0648\u0644 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0628\u0647 \u0635\u0648\u0631\u062a \u0631\u0627\u06cc\u06af\u0627\u0646 \u0648 \u062c\u0644\u062f \u062f\u0648\u0645 \u0622\u0646 \u0628\u0627 \u0635\u0631\u0641 \u0647\u0632\u06cc\u0646\u0647 \u0627\u0646\u062f\u06a9 \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0645\u0648\u062c\u0648\u062f \u0645\u06cc \u0628\u0627\u0634\u062f \u0648 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0622\u0646 \u0647\u0627 \u0631\u0627 \u062f\u0631 \u06a9\u062a\u0627\u0628\u062e\u0648\u0627\u0646 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u067e\u0633 \u0627\u0632 \u062f\u0627\u0646\u0644\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0648 \u0645\u0637\u0627\u0644\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B3%D9%84%D8%A7%D9%85_%D8%A8%D8%B1_%D8%A7%D8%A8%D8%B1%D8%A7%D9%87%DB%8C%D9%85_%D8%B5%D9%88%D8%AA%DB%8C\"><\/span>\u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0635\u0648\u062a\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u06a9\u062a\u0627\u0628 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0645\u0648\u062c\u0648\u062f \u0646\u0645\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>\u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u06f2 \u06a9\u0627\u0631\u06cc \u0627\u0632 \u06af\u0631\u0648\u0647 \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646 \u0627\u0646\u062c\u0645\u0646 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u0645\u06cc\u200c\u0628\u0627\u0634\u062f \u0648 \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0634\u0647\u06cc\u062f \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0686\u0627\u067e \u0631\u0633\u0627\u0646\u062f\u0647 \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2\u00a0\u0631\u0627 \u062a\u0642\u062f\u06cc\u0645\u062a\u0627\u0646 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645. \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 \u0647\u0627\u062f\u06cc \u0627\u0633\u062a\u0627\u062f \u067e\u0646\u0627\u0647\u064a\u0627\u0646 \u062f\u0631 \u064a\u0627\u062f\u0648\u0627\u0631\u0647 \u0634\u0647\u062f\u0627\u064a \u06a9\u0627\u0646\u0627\u0644 \u06a9\u0645\u064a\u0644 \u062f\u0631 \u0631\u0648\u0632 \u062c\u0648\u0627\u0646\u060c \u062e\u0631\u062f\u0627\u062f\u0645\u0627\u0647 \u06f1\u06f3\u06f9\u06f4 \u062f\u0631\u0628\u0627\u0631\u0647 \u0627\u06cc \u0634\u0647\u06cc\u062f \u0628\u0632\u0631\u06af\u0648\u0627\u0631 \u06af\u0641\u062a\u0646\u062f: \u0634\u0647\u064a\u062f [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":3632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[70],"tags":[],"class_list":["post-3629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-book-summary"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2<\/title>\n<meta name=\"description\" content=\"\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647\u0645\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062c\u0644\u062f \u0627\u0648\u0644 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062a\u0648\u0633\u0637 \u0646\u0634\u0631 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0639\u0631\u0636\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.faraketab.ir\/blog\/\u062e\u0644\u0627\u0635\u0647-\u06a9\u062a\u0627\u0628-\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-2\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2\" \/>\n<meta property=\"og:description\" content=\"\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647\u0645\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062c\u0644\u062f \u0627\u0648\u0644 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062a\u0648\u0633\u0637 \u0646\u0634\u0631 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0639\u0631\u0636\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.faraketab.ir\/blog\/\u062e\u0644\u0627\u0635\u0647-\u06a9\u062a\u0627\u0628-\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-2\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-14T10:23:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-18T11:17:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2023\/05\/\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-\u062c\u0644\u062f-\u062f\u0648\u0645.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/\"},\"author\":{\"name\":\"\u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#\\\/schema\\\/person\\\/11d82208d6986e1ed69f73e49fb65b05\"},\"headline\":\"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2\",\"datePublished\":\"2023-05-14T10:23:05+00:00\",\"dateModified\":\"2024-07-18T11:17:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/\"},\"wordCount\":4,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-\u062c\u0644\u062f-\u062f\u0648\u0645.jpg\",\"articleSection\":[\"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/\",\"name\":\"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-\u062c\u0644\u062f-\u062f\u0648\u0645.jpg\",\"datePublished\":\"2023-05-14T10:23:05+00:00\",\"dateModified\":\"2024-07-18T11:17:17+00:00\",\"description\":\"\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647\u0645\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062c\u0644\u062f \u0627\u0648\u0644 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062a\u0648\u0633\u0637 \u0646\u0634\u0631 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0639\u0631\u0636\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-\u062c\u0644\u062f-\u062f\u0648\u0645.jpg\",\"contentUrl\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-\u062c\u0644\u062f-\u062f\u0648\u0645.jpg\",\"width\":1000,\"height\":667,\"caption\":\"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/\",\"name\":\"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#organization\",\"name\":\"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-faraketab.png\",\"contentUrl\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-faraketab.png\",\"width\":420,\"height\":432,\"caption\":\"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628\"},\"image\":{\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/#\\\/schema\\\/person\\\/11d82208d6986e1ed69f73e49fb65b05\",\"name\":\"\u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e30f79b57396c162507f66d2660839c3af1f480f257678036425b37ef113fc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e30f79b57396c162507f66d2660839c3af1f480f257678036425b37ef113fc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e30f79b57396c162507f66d2660839c3af1f480f257678036425b37ef113fc?s=96&d=mm&r=g\",\"caption\":\"\u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc\"},\"description\":\"\u0645\u0646 \u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc \u0647\u0633\u062a\u0645. \u0641\u0627\u0631\u063a \u0627\u0644\u062a\u062d\u0635\u06cc\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0641\u0646\u200c\u0622\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0648 \u0627\u0632 \u0633\u0627\u0644 1392 \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u062f\u0631 \u062d\u0627\u0644 \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0633\u062a\u0645. \u0628\u0627 \u0635\u062f\u0647\u0627 \u0646\u0627\u0634\u0631 \u0648 \u0646\u0648\u06cc\u0633\u0646\u062f\u0647 \u0628\u0631\u0627\u06cc \u0634\u0631\u0648\u0639 \u062a\u0639\u0627\u0645\u0644 \u0645\u0630\u0627\u06a9\u0631\u0647 \u06a9\u0631\u062f\u0647\u200c\u0627\u0645 \u0648 \u0639\u0645\u06cc\u0642\u0627 \u062f\u0648\u0633\u062a\u062f\u0627\u0631 \u0622\u0646\u0645\u060c \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u062f\u0646\u0628\u0627\u0644 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0641\u0631\u0627\u0648\u0627\u0646 \u0648 \u0633\u0637\u062d\u06cc\u200c\u0627\u0646\u062f \u0628\u0647 \u062c\u0645\u0639 \u06a9\u062a\u0627\u0628\u200c\u062e\u0648\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u067e\u06cc \u062f\u0627\u0646\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u0642\u06cc\u200c\u0627\u0646\u062f \u0628\u067e\u06cc\u0648\u0646\u062f\u0646\u062f!!\",\"url\":\"https:\\\/\\\/www.faraketab.ir\\\/blog\\\/author\\\/mahdavi\\\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2","description":"\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647\u0645\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062c\u0644\u062f \u0627\u0648\u0644 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062a\u0648\u0633\u0637 \u0646\u0634\u0631 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0639\u0631\u0636\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.faraketab.ir\/blog\/\u062e\u0644\u0627\u0635\u0647-\u06a9\u062a\u0627\u0628-\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-2\/","og_locale":"fa_IR","og_type":"article","og_title":"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2","og_description":"\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647\u0645\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062c\u0644\u062f \u0627\u0648\u0644 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062a\u0648\u0633\u0637 \u0646\u0634\u0631 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0639\u0631\u0636\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a","og_url":"https:\/\/www.faraketab.ir\/blog\/\u062e\u0644\u0627\u0635\u0647-\u06a9\u062a\u0627\u0628-\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-2\/","og_site_name":"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628","article_published_time":"2023-05-14T10:23:05+00:00","article_modified_time":"2024-07-18T11:17:17+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2023\/05\/\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-\u062c\u0644\u062f-\u062f\u0648\u0645.jpg","type":"image\/jpeg"}],"author":"\u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc","twitter_card":"summary_large_image","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"\u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc","\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646":"7 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#article","isPartOf":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/"},"author":{"name":"\u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc","@id":"https:\/\/www.faraketab.ir\/blog\/#\/schema\/person\/11d82208d6986e1ed69f73e49fb65b05"},"headline":"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2","datePublished":"2023-05-14T10:23:05+00:00","dateModified":"2024-07-18T11:17:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/"},"wordCount":4,"commentCount":0,"publisher":{"@id":"https:\/\/www.faraketab.ir\/blog\/#organization"},"image":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2023\/05\/\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-\u062c\u0644\u062f-\u062f\u0648\u0645.jpg","articleSection":["\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/","url":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/","name":"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2","isPartOf":{"@id":"https:\/\/www.faraketab.ir\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#primaryimage"},"image":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2023\/05\/\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-\u062c\u0644\u062f-\u062f\u0648\u0645.jpg","datePublished":"2023-05-14T10:23:05+00:00","dateModified":"2024-07-18T11:17:17+00:00","description":"\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647\u0645\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062c\u0644\u062f \u0627\u0648\u0644 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062a\u0648\u0633\u0637 \u0646\u0634\u0631 \u0634\u0647\u06cc\u062f \u0647\u0627\u062f\u06cc \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u0639\u0631\u0636\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a","breadcrumb":{"@id":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#primaryimage","url":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2023\/05\/\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-\u062c\u0644\u062f-\u062f\u0648\u0645.jpg","contentUrl":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2023\/05\/\u0633\u0644\u0627\u0645-\u0628\u0631-\u0627\u0628\u0631\u0627\u0647\u06cc\u0645-\u062c\u0644\u062f-\u062f\u0648\u0645.jpg","width":1000,"height":667,"caption":"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2"},{"@type":"BreadcrumbList","@id":"https:\/\/www.faraketab.ir\/blog\/%d8%ae%d9%84%d8%a7%d8%b5%d9%87-%da%a9%d8%aa%d8%a7%d8%a8-%d8%b3%d9%84%d8%a7%d9%85-%d8%a8%d8%b1-%d8%a7%d8%a8%d8%b1%d8%a7%d9%87%db%8c%d9%85-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/www.faraketab.ir\/blog\/"},{"@type":"ListItem","position":2,"name":"\u062e\u0644\u0627\u0635\u0647 \u06a9\u062a\u0627\u0628 \u0633\u0644\u0627\u0645 \u0628\u0631 \u0627\u0628\u0631\u0627\u0647\u06cc\u0645 2"}]},{"@type":"WebSite","@id":"https:\/\/www.faraketab.ir\/blog\/#website","url":"https:\/\/www.faraketab.ir\/blog\/","name":"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628","description":"","publisher":{"@id":"https:\/\/www.faraketab.ir\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.faraketab.ir\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/www.faraketab.ir\/blog\/#organization","name":"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628","url":"https:\/\/www.faraketab.ir\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/www.faraketab.ir\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2025\/06\/logo-faraketab.png","contentUrl":"https:\/\/www.faraketab.ir\/blog\/wp-content\/uploads\/2025\/06\/logo-faraketab.png","width":420,"height":432,"caption":"\u0645\u062c\u0644\u0647 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628"},"image":{"@id":"https:\/\/www.faraketab.ir\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.faraketab.ir\/blog\/#\/schema\/person\/11d82208d6986e1ed69f73e49fb65b05","name":"\u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/secure.gravatar.com\/avatar\/a1e30f79b57396c162507f66d2660839c3af1f480f257678036425b37ef113fc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1e30f79b57396c162507f66d2660839c3af1f480f257678036425b37ef113fc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1e30f79b57396c162507f66d2660839c3af1f480f257678036425b37ef113fc?s=96&d=mm&r=g","caption":"\u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc"},"description":"\u0645\u0646 \u0639\u0644\u06cc \u0645\u0647\u062f\u0648\u06cc \u0647\u0633\u062a\u0645. \u0641\u0627\u0631\u063a \u0627\u0644\u062a\u062d\u0635\u06cc\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0641\u0646\u200c\u0622\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0648 \u0627\u0632 \u0633\u0627\u0644 1392 \u062f\u0631 \u0641\u0631\u0627\u06a9\u062a\u0627\u0628 \u062f\u0631 \u062d\u0627\u0644 \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0633\u062a\u0645. \u0628\u0627 \u0635\u062f\u0647\u0627 \u0646\u0627\u0634\u0631 \u0648 \u0646\u0648\u06cc\u0633\u0646\u062f\u0647 \u0628\u0631\u0627\u06cc \u0634\u0631\u0648\u0639 \u062a\u0639\u0627\u0645\u0644 \u0645\u0630\u0627\u06a9\u0631\u0647 \u06a9\u0631\u062f\u0647\u200c\u0627\u0645 \u0648 \u0639\u0645\u06cc\u0642\u0627 \u062f\u0648\u0633\u062a\u062f\u0627\u0631 \u0622\u0646\u0645\u060c \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u062f\u0646\u0628\u0627\u0644 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0641\u0631\u0627\u0648\u0627\u0646 \u0648 \u0633\u0637\u062d\u06cc\u200c\u0627\u0646\u062f \u0628\u0647 \u062c\u0645\u0639 \u06a9\u062a\u0627\u0628\u200c\u062e\u0648\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u067e\u06cc \u062f\u0627\u0646\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u0642\u06cc\u200c\u0627\u0646\u062f \u0628\u067e\u06cc\u0648\u0646\u062f\u0646\u062f!!","url":"https:\/\/www.faraketab.ir\/blog\/author\/mahdavi\/"},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":15,"sum_votes":63},"_links":{"self":[{"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/posts\/3629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/comments?post=3629"}],"version-history":[{"count":6,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/posts\/3629\/revisions"}],"predecessor-version":[{"id":9921,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/posts\/3629\/revisions\/9921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/media\/3632"}],"wp:attachment":[{"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/media?parent=3629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/categories?post=3629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.faraketab.ir\/blog\/wp-json\/wp\/v2\/tags?post=3629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}